{"id":1324,"date":"2025-11-08T10:12:44","date_gmt":"2025-11-08T02:12:44","guid":{"rendered":"http:\/\/wp.yantaisensor.com\/?post_type=product&#038;p=1324"},"modified":"2026-05-09T12:01:06","modified_gmt":"2026-05-09T04:01:06","slug":"microfono-sensor-de-ruido-exterior","status":"publish","type":"product","link":"https:\/\/www.yantaisensor.com\/es\/product\/microphone-outdoor-noise-sensor","title":{"rendered":"Sensor de ruido para exteriores RY-CZS\/485 Micr\u00f3fono con salida digital RS485 Tube Smart"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1324_198c49-31{margin-top:-30px;}.kb-row-layout-id1324_198c49-31 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_198c49-31 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_198c49-31 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id1324_198c49-31 > .kt-row-layout-overlay{opacity:0.95;background-color:#f0f2f4;}@media all and (max-width: 1024px){.kb-row-layout-id1324_198c49-31 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1324_198c49-31 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_198c49-31 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1324_fa4185-7a > .kt-inside-inner-col,.kadence-column1324_fa4185-7a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_fa4185-7a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_fa4185-7a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_fa4185-7a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_fa4185-7a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_fa4185-7a{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_fa4185-7a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_fa4185-7a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_fa4185-7a\"><div class=\"kt-inside-inner-col\"><style>.kb-gallery-type-thumbslider.kb-gallery-id-1324_60df10-e3 .kt-blocks-carousel-init {margin-bottom:10px;}.kb-gallery-id-1324_60df10-e3 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1324_60df10-e3 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-1324_60df10-e3 alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-thumbslider kb-gallery-id-1324_60df10-e3 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div id=\"kb-slider-1324_60df10-e3\" class=\"kt-blocks-carousel-init splide kb-blocks-slider kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"4\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-thumb-slider-1324_60df10-e3\"  data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-gap=\"10px\" data-slider-gap-tablet=\"10px\" data-slider-gap-mobile=\"10px\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2.webp\" width=\"800\" height=\"600\" alt=\"Tube\u00a0Smart RS485 Digital Output Microphone Outdoor Noise Sensor\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2.webp\" data-id=\"3970\" class=\"wp-image-3970 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7.webp\" width=\"800\" height=\"600\" alt=\"Tube\u00a0Smart RS485 Digital Output Microphone Outdoor Noise Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7.webp\" data-id=\"3975\" class=\"wp-image-3975 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6.webp\" width=\"800\" height=\"600\" alt=\"Tube\u00a0Smart RS485 Digital Output Microphone Outdoor Noise Sensor\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6.webp\" data-id=\"3974\" class=\"wp-image-3974 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><div id=\"kb-thumb-slider-1324_60df10-e3\" class=\"kb-blocks-slider splide kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-speed=\"7000\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-slider-1324_60df10-e3\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2.webp\" width=\"800\" height=\"600\" alt=\"Tube\u00a0Smart RS485 Digital Output Microphone Outdoor Noise Sensor\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2.webp\" data-id=\"3970\" class=\"wp-image-3970 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-2-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7.webp\" width=\"800\" height=\"600\" alt=\"Tube\u00a0Smart RS485 Digital Output Microphone Outdoor Noise Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7.webp\" data-id=\"3975\" class=\"wp-image-3975 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6.webp\" width=\"800\" height=\"600\" alt=\"Tube\u00a0Smart RS485 Digital Output Microphone Outdoor Noise Sensor\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6.webp\" data-id=\"3974\" class=\"wp-image-3974 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-6-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column1324_a400a7-3c > .kt-inside-inner-col,.kadence-column1324_a400a7-3c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_a400a7-3c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_a400a7-3c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_a400a7-3c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_a400a7-3c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_a400a7-3c{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_a400a7-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_a400a7-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_a400a7-3c\"><div class=\"kt-inside-inner-col\">\n<h1 class=\"wp-block-heading has-large-font-size\">RY-CZS\/485 Tube&nbsp;Smart RS485 Digital Output Microphone Outdoor Noise Sensor<\/h1>\n\n\n\n<p class=\"has-text-align-left\" style=\"font-size:18px\">RY-CZS\/485 Tube Smart RS485 Digital Output Microphone Outdoor Noise Sensor is a smart integrated noise sensor specifically designed for outdoor and industrial applications. Featuring a tubular stainless steel housing, it incorporates a high-sensitivity condenser microphone and digital processing circuitry to accurately detect and calculate environmental decibel levels. This noise sensor offers high protection ratings and easy installation, making it an ideal choice for environmental monitoring and industrial safety applications.<\/p>\n\n\n<style>.kb-table-container1324_7309e9-bf{overflow-x:auto;}.kb-table-container .kb-table1324_7309e9-bf th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table1324_7309e9-bf caption{text-align:center;}.kb-table-container .kb-table1324_7309e9-bf td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}.kb-table-container .kb-table1324_7309e9-bf tr:nth-of-type(odd){background-color:rgba(225,225,225,0.55);}.kb-table-container .kb-table1324_7309e9-bf td, .kb-table1324_7309e9-bf th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}@media all and (max-width: 1024px){.kb-table-container .kb-table1324_7309e9-bf td, .kb-table1324_7309e9-bf th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-table-container .kb-table1324_7309e9-bf td, .kb-table1324_7309e9-bf th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-table-container kb-table-container1324_7309e9-bf wp-block-kadence-table\"><table class=\"kb-table kb-table1324_7309e9-bf\">\n<tr class=\"kb-table-row kb-table-row1324_7a83a3-fa\">\n<th class=\"kb-table-data kb-table-data1324_e476e4-e1\">\n\n<p><strong>Parameter<\/strong><\/p>\n\n<\/th>\n\n<th class=\"kb-table-data kb-table-data1324_fe237f-b5\">\n\n<p><strong>Specification<\/strong><\/p>\n\n<\/th>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1324_48e2b8-b9\">\n<td class=\"kb-table-data kb-table-data1324_76b3d3-45\">\n\n<p>Measuring Range<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1324_d2a37c-fe\">\n\n<p>30~130dB<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1324_6849ca-3f\">\n<td class=\"kb-table-data kb-table-data1324_4b4930-f0\">\n\n<p>Output<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1324_cefade-5b\">\n\n<p>RS485<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1324_26011a-0e\">\n<td class=\"kb-table-data kb-table-data1324_747857-7c\">\n\n<p>Accuracy(23\u00b15\u2103)<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1324_ae51ce-0e\">\n\n<p>-1.5db ~1.5db<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1324_51f258-fd\">\n<td class=\"kb-table-data kb-table-data1324_710753-bd\">\n\n<p>Frequency Range<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1324_8495dd-9f\">\n\n<p>31.5Hz ~ 12.5kHz<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1324_34bea4-ff\">\n<td class=\"kb-table-data kb-table-data1324_03ad7b-00\">\n\n<p>Range selection<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1324_888b33-d0\">\n\n<p>30~130dB<\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n<!-- [element-4655] --><style>.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{display:flex;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{padding-left:0px;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col,.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4655_6bf1b4-cc{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4655_6bf1b4-cc{position:relative;}.kadence-column4655_6bf1b4-cc, .kt-inside-inner-col > .kadence-column4655_6bf1b4-cc:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4655_6bf1b4-cc{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column4655_6bf1b4-cc{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4655_6bf1b4-cc\"><div class=\"kt-inside-inner-col\"><style>#kt-modal4655_8bf53c-60 .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px px;}#kt-modal4655_8bf53c-60 .kt-blocks-modal-link:hover, #kt-modal4655_8bf53c-60 .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal4655_8bf53c-60 .kt-modal-overlay, #kt-target-modal4655_8bf53c-60 .kt-modal-overlay, .kb-modal-content4655_8bf53c-60 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{width:45%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal4655_8bf53c-60 .kt-modal-close svg, #kt-target-modal4655_8bf53c-60 .kt-modal-close svg, .kb-modal-content4655_8bf53c-60 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal4655_8bf53c-60 .kt-modal-close svg, #kt-target-modal4655_8bf53c-60 .kt-modal-close svg, .kb-modal-content4655_8bf53c-60 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal4655_8bf53c-60 .kt-modal-close svg, #kt-target-modal4655_8bf53c-60 .kt-modal-close svg, .kb-modal-content4655_8bf53c-60 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal aligncenter kt-modal-linkalign-left\" id=\"kt-modal4655_8bf53c-60\"><div id=\"kt-target-modal4655_8bf53c-60\" class=\"kb-modal-content4655_8bf53c-60 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal4655_8bf53c-60-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-4655_273dee-56 .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);}.kadence-form-4655_273dee-56 .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-4655_273dee-56 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_4655_273dee-56_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_4655_273dee-56_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_4655_273dee-56_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_4655_273dee-56_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_4655_273dee-56_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_4655_273dee-56_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_4655_273dee-56_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_4655_273dee-56_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"4655_273dee-56\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"4655\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\"><strong>SUBMIT<\/strong><\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Activar JavaScript en tu navegador para enviar el formulario<\/div><style>.kadence-form-4655_273dee-56 .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal4655_8bf53c-60\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-4655] -->\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1324_7d9c7e-95 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_7d9c7e-95 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_7d9c7e-95 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1324_7d9c7e-95 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1324_7d9c7e-95 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1324_7d9c7e-95 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_7d9c7e-95 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1324_9596d8-e2 > .kt-inside-inner-col,.kadence-column1324_9596d8-e2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_9596d8-e2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_9596d8-e2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_9596d8-e2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_9596d8-e2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_9596d8-e2{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_9596d8-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_9596d8-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_9596d8-e2\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Introduction<\/h2>\n\n\n\n<p>This Outdoor Noise Sensor utilizes a standard RS485 (Modbus-RTU) digital interface, allowing users to seamlessly integrate real-time noise data into PLCs, environmental monitoring hosts, or cloud platforms. This enables remote, long-distance, and highly interference-resistant automated noise monitoring.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1324_132847-d0 > .kt-inside-inner-col,.kadence-column1324_132847-d0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_132847-d0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_132847-d0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_132847-d0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_132847-d0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_132847-d0{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_132847-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_132847-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_132847-d0\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"202\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/3.avif\" alt=\"ry czs environment sound monitor outdoor air quality sensor industrial decibel noise detector noise sensor\" class=\"wp-image-1327\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/3.avif 480w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/3-300x126.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">Details Show<\/h2>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-1324_d65646-c1{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-1324_d65646-c1 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-1324_d65646-c1 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1324_d65646-c1 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-1324_d65646-c1 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-1324_d65646-c1 kb-gallery-caption-style-bottom-hover kb-gallery-filter-mayfair\" data-image-filter=\"mayfair\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-3.webp\" width=\"800\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-3.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-3.webp\" data-id=\"3971\" class=\"wp-image-3971\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-3.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-3-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-3-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-3-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-4.webp\" width=\"800\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-4.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-4.webp\" data-id=\"3972\" class=\"wp-image-3972\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-4.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-4-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-4-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-4-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-5.webp\" width=\"800\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-5.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-5.webp\" data-id=\"3973\" class=\"wp-image-3973\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-5.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-5-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-5-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-5-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<h2 class=\"wp-block-heading\">Specifications<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\"><strong>Item<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>Technical Specification<\/strong><\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Range<\/td><td class=\"has-text-align-center\" data-align=\"center\">30-130dB<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Accuracy<\/td><td class=\"has-text-align-center\" data-align=\"center\">\u00b13dB@23\u00b15\u2103,accordance with IEC 61672 standard type 2,&nbsp;calibrated at 94dB(1kHz) input<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Frequency response<\/td><td class=\"has-text-align-center\" data-align=\"center\">20Hz-12.5kHz<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Corrector<\/td><td class=\"has-text-align-center\" data-align=\"center\">B&amp;K 4231<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Microphone<\/td><td class=\"has-text-align-center\" data-align=\"center\">Capacitive microphone , size: 0.5 inch<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Supply<\/td><td class=\"has-text-align-center\" data-align=\"center\">5VDC,12-24VDC<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Output<\/td><td class=\"has-text-align-center\" data-align=\"center\">RS485<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Power Consumption<\/td><td class=\"has-text-align-center\" data-align=\"center\">&lt;0.5W@12VDC<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Response Time<\/td><td class=\"has-text-align-center\" data-align=\"center\">&lt;200ms<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Operating Temperature<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a>-20<\/a>\u2103-+80\u2103@5-80%RH<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Storage<\/td><td class=\"has-text-align-center\" data-align=\"center\">-40-80\u2103@20%-90%RH<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Shell Material<\/td><td class=\"has-text-align-center\" data-align=\"center\">Aluminum alloy<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<style>.kb-row-layout-id1324_ff3e19-a3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_ff3e19-a3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_ff3e19-a3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1324_ff3e19-a3 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-bottom-sep svg{fill:var(--global-palette9, #ffffff)!important;}.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-top-sep{height:100px;}.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-top-sep svg{width:100%;}.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-top-sep svg{fill:var(--global-palette9, #ffffff)!important;}@media all and (max-width: 1024px){.kb-row-layout-id1324_ff3e19-a3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id1324_ff3e19-a3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id1324_ff3e19-a3 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_ff3e19-a3 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1324_6e071a-bd > .kt-inside-inner-col,.kadence-column1324_6e071a-bd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_6e071a-bd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_6e071a-bd > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_6e071a-bd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_6e071a-bd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_6e071a-bd{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_6e071a-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_6e071a-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_6e071a-bd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1324_e9d136-a8, .wp-block-kadence-advancedheading.kt-adv-heading1324_e9d136-a8[data-kb-block=\"kb-adv-heading1324_e9d136-a8\"]{margin-top:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1.1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1324_e9d136-a8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1324_e9d136-a8[data-kb-block=\"kb-adv-heading1324_e9d136-a8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1324_e9d136-a8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1324_e9d136-a8[data-kb-block=\"kb-adv-heading1324_e9d136-a8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1324_e9d136-a8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1324_e9d136-a8\">Features<\/h2>\n\n\n<style>.kb-row-layout-id1324_73e6ff-97 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_73e6ff-97 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_73e6ff-97 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id1324_73e6ff-97 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1324_73e6ff-97 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1324_73e6ff-97 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1324_73e6ff-97 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1324_73e6ff-97 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1324_73e6ff-97 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1324_73e6ff-97 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_73e6ff-97 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1324_9d9141-4d > .kt-inside-inner-col,.kadence-column1324_9d9141-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_9d9141-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_9d9141-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_9d9141-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_9d9141-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_9d9141-4d{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_9d9141-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_9d9141-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_9d9141-4d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1324_4a7e7d-3f .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1324_4a7e7d-3f .kt-info-svg-icon-flip, .kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1324_4a7e7d-3f .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1324_4a7e7d-3f .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_4a7e7d-3f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1324_4a7e7d-3f\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowUpCircle kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"16 12 12 8 8 12\"\/><line x1=\"12\" y1=\"16\" x2=\"12\" y2=\"8\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Probe-Style\/Tube Design<\/h3><p class=\"kt-blocks-info-box-text\">Features a tubular housing made of stainless steel or high-density polymer, offering a compact structure that facilitates easy installation via threaded connections or mounting brackets.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1324_c3399f-92 > .kt-inside-inner-col,.kadence-column1324_c3399f-92 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_c3399f-92 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_c3399f-92 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_c3399f-92 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_c3399f-92 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_c3399f-92{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_c3399f-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_c3399f-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_c3399f-92\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1324_fe1e85-e0 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1324_fe1e85-e0 .kt-info-svg-icon-flip, .kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1324_fe1e85-e0 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1324_fe1e85-e0 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_fe1e85-e0 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1324_fe1e85-e0\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Weather Resistance and Compact Design<\/h3><p class=\"kt-blocks-info-box-text\">The housing provides excellent protection against rain and snow, withstanding harsh weather conditions. Its small, lightweight form enables rapid installation in diverse challenging outdoor environments.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1324_e1c9a7-d7 > .kt-inside-inner-col,.kadence-column1324_e1c9a7-d7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_e1c9a7-d7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_e1c9a7-d7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_e1c9a7-d7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_e1c9a7-d7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_e1c9a7-d7{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_e1c9a7-d7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_e1c9a7-d7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_e1c9a7-d7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1324_57c1c9-cd .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1324_57c1c9-cd .kt-info-svg-icon-flip, .kt-info-box1324_57c1c9-cd .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1324_57c1c9-cd .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1324_57c1c9-cd .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_57c1c9-cd .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1324_57c1c9-cd\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_box kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M12.89 1.45l8 4A2 2 0 0 1 22 7.24v9.53a2 2 0 0 1-1.11 1.79l-8 4a2 2 0 0 1-1.79 0l-8-4a2 2 0 0 1-1.1-1.8V7.24a2 2 0 0 1 1.11-1.79l8-4a2 2 0 0 1 1.78 0z\"\/><polyline points=\"2.32 6.16 12 11 21.68 6.16\"\/><line x1=\"12\" y1=\"22.76\" x2=\"12\" y2=\"11\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">High-Precision Digital Output<\/h3><p class=\"kt-blocks-info-box-text\">Incorporates a high-sensitivity condenser microphone and a digital signal processing (DSP) chip with A-weighted (simulating human ear perception) frequency processing, typically achieving measurement accuracy of \u00b10.5 dB.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1324_fdb640-29 > .kt-inside-inner-col,.kadence-column1324_fdb640-29 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_fdb640-29 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_fdb640-29 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_fdb640-29 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_fdb640-29 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_fdb640-29{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_fdb640-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_fdb640-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_fdb640-29\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1324_49cf34-7c .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1324_49cf34-7c .kt-info-svg-icon-flip, .kt-info-box1324_49cf34-7c .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1324_49cf34-7c .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1324_49cf34-7c .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_49cf34-7c .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1324_49cf34-7c\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_airplay kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M5 17H4a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h16a2 2 0 0 1 2 2v10a2 2 0 0 1-2 2h-1\"\/><polygon points=\"12 15 17 21 7 21 12 15\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong>RS485 Communication Interface<\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Utilizes the standard Modbus-RTU protocol. Compared to analog signals (e.g., 4-20mA), digital output offers superior interference resistance, supports multi-point networking, and enables transmission distances exceeding 1000 meters.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1324_818fd3-3a > .kt-inside-inner-col,.kadence-column1324_818fd3-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_818fd3-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_818fd3-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_818fd3-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_818fd3-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_818fd3-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_818fd3-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_818fd3-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_818fd3-3a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1324_52d6d9-f1 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1324_52d6d9-f1 .kt-info-svg-icon-flip, .kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1324_52d6d9-f1 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1324_52d6d9-f1 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_52d6d9-f1 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1324_52d6d9-f1\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_codepen kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"12 2 22 8.5 22 15.5 12 22 2 15.5 2 8.5 12 2\"\/><line x1=\"12\" y1=\"22\" x2=\"12\" y2=\"15.5\"\/><polyline points=\"22 8.5 12 15.5 2 8.5\"\/><polyline points=\"2 15.5 12 8.5 22 15.5\"\/><line x1=\"12\" y1=\"2\" x2=\"12\" y2=\"8.5\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong>Wide-range measurement<\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Typically covers 30 dB (quiet environments) to 130 dB (industrial high noise), with a broad frequency response span (e.g., 20 Hz to 12.5 kHz).<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1324_e0fc6c-b7 > .kt-inside-inner-col,.kadence-column1324_e0fc6c-b7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_e0fc6c-b7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_e0fc6c-b7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_e0fc6c-b7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_e0fc6c-b7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_e0fc6c-b7{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_e0fc6c-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_e0fc6c-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_e0fc6c-b7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1324_7cb18c-0f .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1324_7cb18c-0f .kt-info-svg-icon-flip, .kt-info-box1324_7cb18c-0f .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1324_7cb18c-0f .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1324_7cb18c-0f .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1324_7cb18c-0f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1324_7cb18c-0f\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit2 kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"16 3 21 8 8 21 3 21 3 16 16 3\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong>All-weather monitoring<\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Typically equipped with an anemometer cup\/rain cover to effectively reduce wind noise interference and protect internal sensor components from moisture damage.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1324_8b1712-ed{margin-top:0px;}.kb-row-layout-id1324_8b1712-ed > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_8b1712-ed > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_8b1712-ed > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1324_8b1712-ed > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1324_8b1712-ed > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1324_8b1712-ed > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_8b1712-ed alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1324_278867-e4 > .kt-inside-inner-col,.kadence-column1324_278867-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_278867-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_278867-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_278867-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_278867-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_278867-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_278867-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_278867-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_278867-e4\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Application<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1324_8e891b-02 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_8e891b-02 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_8e891b-02 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-row-layout-id1324_8e891b-02 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1324_8e891b-02 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id1324_8e891b-02 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1324_8e891b-02 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1324_8e891b-02 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1324_8e891b-02 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1324_8e891b-02 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_8e891b-02 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1324_aa1397-6e > .kt-inside-inner-col,.kadence-column1324_aa1397-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_aa1397-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_aa1397-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_aa1397-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_aa1397-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_aa1397-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_aa1397-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_aa1397-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_aa1397-6e\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"413\" height=\"310\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Grid-based-Environmental-Monitoring-edited-1.webp\" alt=\"Grid-based Environmental Monitoring\" class=\"wp-image-3942\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Grid-based-Environmental-Monitoring-edited-1.webp 413w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Grid-based-Environmental-Monitoring-edited-1-300x225.webp 300w\" sizes=\"auto, (max-width: 413px) 100vw, 413px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Smart Cities and Environmental Monitoring<\/h3>\n\n\n\n<p>Installed on streetlight poles or at traffic intersections to monitor urban environmental noise pollution in real time.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1324_f641b3-ac > .kt-inside-inner-col,.kadence-column1324_f641b3-ac > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_f641b3-ac > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_f641b3-ac > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_f641b3-ac > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_f641b3-ac > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_f641b3-ac{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_f641b3-ac > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_f641b3-ac > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_f641b3-ac\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Wastewater-Treatment-Solutions-2-1.webp\" alt=\"Wastewater Treatment Solutions\" class=\"wp-image-3545\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Wastewater-Treatment-Solutions-2-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Wastewater-Treatment-Solutions-2-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Wastewater-Treatment-Solutions-2-1-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">Industrial Parks and Factories<\/h2>\n\n\n\n<p>Monitor operational noise in workshops, machine rooms, and large equipment (such as air compressors and cooling towers) to prevent noise violations or enable equipment failure early warning.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1324_41f652-c9 > .kt-inside-inner-col,.kadence-column1324_41f652-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_41f652-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_41f652-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_41f652-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_41f652-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_41f652-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_41f652-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_41f652-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_41f652-c9\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Wastewater-Treatment-Solutions-24.webp\" alt=\"Wastewater Treatment Solutions\" class=\"wp-image-3548\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Wastewater-Treatment-Solutions-24.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Wastewater-Treatment-Solutions-24-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Wastewater-Treatment-Solutions-24-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Construction Sites<\/h3>\n\n\n\n<p>Meet environmental protection agencies&#8217; requirements for decibel monitoring at construction sites and trigger alarms when levels exceed standards.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1324_30df3c-8f > .kt-inside-inner-col,.kadence-column1324_30df3c-8f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_30df3c-8f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_30df3c-8f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_30df3c-8f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_30df3c-8f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_30df3c-8f{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_30df3c-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_30df3c-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_30df3c-8f\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Traffic-sensors-edited.webp\" alt=\"Traffic Sensors Solutions\" class=\"wp-image-3943\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Traffic-sensors-edited.webp 960w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Traffic-sensors-edited-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Traffic-sensors-edited-768x576.webp 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Traffic Monitoring<\/h3>\n\n\n\n<p>Deployed near highways, railways, or airports to assess transportation impacts on surrounding residential areas.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1324_94c255-43 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_94c255-43 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_94c255-43 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1324_94c255-43 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1324_94c255-43 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1324_94c255-43 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_94c255-43 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1324_3de8fc-b0 > .kt-inside-inner-col,.kadence-column1324_3de8fc-b0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_3de8fc-b0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_3de8fc-b0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_3de8fc-b0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_3de8fc-b0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_3de8fc-b0{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_3de8fc-b0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_3de8fc-b0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_3de8fc-b0\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Outdoor Noise Sensor <strong>Manufacturer<\/strong> and Supplier<\/h2>\n\n\n\n<p>Yantai Sensor is a professional manufacturer and supplier of outdoor noise monitoring solutions, providing high-precision noise sensors for environmental monitoring, <a href=\"https:\/\/www.yantaisensor.com\/solutions\/weather-monitoring-solutions\">smart cities<\/a>, industrial sites, construction projects, and traffic noise control. Our sensors feature stable performance, real-time data transmission, weather-resistant design, and easy system integration to meet various outdoor monitoring requirements.<\/p>\n\n\n\n<p>We have a reliable product quality, customized solutions, and comprehensive technical support, Yantai Sensor helps customers build efficient and accurate noise monitoring systems worldwide. Contact us today to get professional recommendations and customized solutions for your project.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-1324_ec3fb0-c9{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-1324_ec3fb0-c9 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-1324_ec3fb0-c9 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1324_ec3fb0-c9 .kb-slide-item .kb-gal-image-radius img{border-radius:15px 15px 15px 15px;;}<\/style><div class=\"kb-gallery-wrap-id-1324_ec3fb0-c9 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-1324_ec3fb0-c9 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp\" data-id=\"2567\" class=\"wp-image-2567\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp\" data-description=\"Professional Weather Station Manufacturer and Supplier\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp\" data-id=\"2568\" class=\"wp-image-2568\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp\" width=\"900\" height=\"598\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp\" data-id=\"2575\" class=\"wp-image-2575\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14-300x199.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14-768x510.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp\" data-id=\"2571\" class=\"wp-image-2571\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp\" data-id=\"2572\" class=\"wp-image-2572\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier (19)\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier (19)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp\" data-id=\"2563\" class=\"wp-image-2563\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier (19)\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier (19)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp\" data-id=\"2580\" class=\"wp-image-2580\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp\" data-id=\"2569\" class=\"wp-image-2569\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<!-- [element-6641] --><style>.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6641_52f583-39 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6641_52f583-39 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6641_9208a2-e5 > .kt-inside-inner-col,.kadence-column6641_9208a2-e5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6641_9208a2-e5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6641_9208a2-e5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6641_9208a2-e5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6641_9208a2-e5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6641_9208a2-e5{position:relative;}@media all and (max-width: 1024px){.kadence-column6641_9208a2-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6641_9208a2-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6641_9208a2-e5\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Certificates<\/h2>\n\n\n\n<p class=\"has-text-align-center\">We have CNAS, ISO, CE, and RoHS certifications, and all weather monitoring systems meet rigorous international standards.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-6641_5f28d1-9d{margin:-10px;}.kb-gallery-type-grid.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item{padding:10px;}.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-6641_5f28d1-9d .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{font-size:var(--global-kb-font-size-md, 1.25rem);}.kb-gallery-caption-style-cover-hover.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption, .kb-gallery-caption-style-below.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{background:var(--global-palette1, #3182CE);}<\/style><div class=\"kb-gallery-wrap-id-6641_5f28d1-9d alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-6641_5f28d1-9d kb-gallery-caption-style-below kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS.webp\" data-description=\"CNAS\" data-alt=\"CNAS\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-port34 kb-has-image-ratio-port34\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS-745x1024.webp\" width=\"745\" height=\"1024\" alt=\"CNAS\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS.webp\" data-id=\"2590\" class=\"wp-image-2590\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS-745x1024.webp 745w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS-218x300.webp 218w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS-768x1056.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS.webp 1000w\" sizes=\"auto, (max-width: 745px) 100vw, 745px\" \/><\/div><\/div><div class=\"kadence-blocks-gallery-item__caption\">CNAS<\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE.webp\" data-description=\"CE\" data-alt=\"CE\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-port34 kb-has-image-ratio-port34\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-725x1024.webp\" width=\"725\" height=\"1024\" alt=\"CE\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE.webp\" data-id=\"6669\" class=\"wp-image-6669\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-725x1024.webp 725w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-212x300.webp 212w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-768x1085.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-1087x1536.webp 1087w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-8x12.webp 8w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE.webp 1200w\" sizes=\"auto, (max-width: 725px) 100vw, 725px\" \/><\/div><\/div><div class=\"kadence-blocks-gallery-item__caption\">CE<\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001.webp\" data-description=\"ISO9001\" data-alt=\"ISO9001\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-port34 kb-has-image-ratio-port34\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001-718x1024.webp\" width=\"718\" height=\"1024\" alt=\"ISO9001\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001.webp\" data-id=\"2591\" class=\"wp-image-2591\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001-718x1024.webp 718w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001-210x300.webp 210w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001-768x1095.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001.webp 1000w\" sizes=\"auto, (max-width: 718px) 100vw, 718px\" \/><\/div><\/div><div class=\"kadence-blocks-gallery-item__caption\">ISO9001<\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS.webp\" data-description=\"RoHS\" data-alt=\"RoHS\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-port34 kb-has-image-ratio-port34\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-725x1024.webp\" width=\"725\" height=\"1024\" alt=\"RoHS\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS.webp\" data-id=\"6671\" class=\"wp-image-6671\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-725x1024.webp 725w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-212x300.webp 212w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-768x1085.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-1087x1536.webp 1087w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-8x12.webp 8w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS.webp 1200w\" sizes=\"auto, (max-width: 725px) 100vw, 725px\" \/><\/div><\/div><div class=\"kadence-blocks-gallery-item__caption\">RoHS<\/div><\/a><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div><!-- [\/element-6641] -->\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1324_87273b-b5{margin-top:var(--global-kb-spacing-md, 2rem);}.kb-row-layout-id1324_87273b-b5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_87273b-b5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_87273b-b5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1324_87273b-b5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1324_87273b-b5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1324_87273b-b5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_87273b-b5 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1324_20e462-72 > .kt-inside-inner-col,.kadence-column1324_20e462-72 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_20e462-72 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_20e462-72 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_20e462-72 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_20e462-72 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_20e462-72{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_20e462-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_20e462-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_20e462-72\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Related Products<\/h2>\n\n\n<style>.kt-post-loop1324_4b3f4a-74 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop1324_4b3f4a-74 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop1324_4b3f4a-74 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop1324_4b3f4a-74 .entry-content:after{height:0px;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop1324_4b3f4a-74 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop1324_4b3f4a-74 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1324_4b3f4a-74.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop1324_4b3f4a-74 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-none kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"false\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kt-post-slider-item post-1388 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/product\/xf200l-ultrasonic-anemometer-sensor\" aria-label=\"XF200L Ultrasonic Anemometer Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF200L Ultrasonic Anemometer\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/product\/xf200l-ultrasonic-anemometer-sensor\">XF200L Ultrasonic Anemometer Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1403 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/product\/xf200as-ultrasonic-anemometer\" aria-label=\"XF200AS Ultrasonic Anemometer\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF200AS Ultrasonic Anemometer\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/product\/xf200as-ultrasonic-anemometer\">XF200AS Ultrasonic Anemometer<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1351 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/product\/xf-cq10-smoke-dust-haze-fog-rain-snow-visibility-sensor\" aria-label=\"XF-CQ10 Smoke Dust Haze Fog Rain Snow Visibility Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"xf cq10 smoke dust haze fog rain snow visibility sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c.jpg 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-300x300.jpg 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-100x100.jpg 100w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-600x600.jpg 600w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-150x150.jpg 150w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/product\/xf-cq10-smoke-dust-haze-fog-rain-snow-visibility-sensor\">XF-CQ10 Smoke Dust Haze Fog Rain Snow Visibility Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-2557 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/product\/weather-station-with-multiple-sensors\" aria-label=\"Weather Station With Multiple Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Weather-Station-With-Multiple-Sensors\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/product\/weather-station-with-multiple-sensors\">Weather Station With Multiple Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1382 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/product\/portable-weather-station-automatic\" aria-label=\"RYQ-2 Portable Weather Station Automatic\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Portable Weather Station Automatic\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7-300x300.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7-150x150.webp 150w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7-768x768.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/product\/portable-weather-station-automatic\">RYQ-2 Portable Weather Station Automatic<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1458 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/product\/xf600a-compact-weather-sensor\" aria-label=\"XF600A temperature Relative humidity Rainfall wind speed direction compact weather sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF600A-compact-weather-sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/product\/xf600a-compact-weather-sensor\">XF600A temperature Relative humidity Rainfall wind speed direction compact weather sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid -->\n\n<style>.kb-row-layout-id1324_3f168f-d0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_3f168f-d0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_3f168f-d0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1324_3f168f-d0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1324_3f168f-d0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1324_3f168f-d0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_3f168f-d0 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1324_39889e-52 > .kt-inside-inner-col,.kadence-column1324_39889e-52 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_39889e-52 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_39889e-52 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_39889e-52 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_39889e-52 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_39889e-52{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_39889e-52 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_39889e-52 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_39889e-52\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Related Articles<\/h2>\n\n\n<style>.kt-post-loop1324_52035a-83 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop1324_52035a-83 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop1324_52035a-83 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop1324_52035a-83 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop1324_52035a-83 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1324_52035a-83 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop1324_52035a-83 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop1324_52035a-83 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop1324_52035a-83 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop1324_52035a-83 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1324_52035a-83 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop1324_52035a-83 .entry-content:after{height:0px;}.kt-post-loop1324_52035a-83 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop1324_52035a-83 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop1324_52035a-83 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1324_52035a-83.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop1324_52035a-83 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-none kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"false\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kt-post-slider-item post-1611 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/blog\/best-weather-station-for-farmers\" aria-label=\"Best weather station for farmers\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-for-farmers-1-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"weather station for farmers\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-for-farmers-1-1.webp 1000w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-for-farmers-1-1-300x180.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-for-farmers-1-1-768x461.webp 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\/best-weather-station-for-farmers\">Best weather station for farmers<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/es\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1618 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/blog\/automatic-weather-station-india\" aria-label=\"Automatic weather station india\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/\u672a\u6807\u9898-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Automatic weather station\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/\u672a\u6807\u9898-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/\u672a\u6807\u9898-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/\u672a\u6807\u9898-1-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\/automatic-weather-station-india\">Automatic weather station india<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/es\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1624 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/blog\/automatic-weather-station-manufacturers\" aria-label=\"Automatic weather station manufacturers\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-manufacturers-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"weather station manufacturers\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-manufacturers-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-manufacturers-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-manufacturers-1-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\/automatic-weather-station-manufacturers\">Automatic weather station manufacturers<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/es\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1348 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/blog\/automatic-outdoor-integrated-environmental-monitoring-equipment\" aria-label=\"Automatic Outdoor Integrated Environmental Monitoring Equipment\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Environmental Monitoring\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-1536x1152.webp 1536w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1.webp 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\/automatic-outdoor-integrated-environmental-monitoring-equipment\">Automatic Outdoor Integrated Environmental Monitoring Equipment<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/es\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1345 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/blog\/sonic-anemometer-high-precision-wind-speed-and-direction-sensor\" aria-label=\"Sonic anemometer &#8211; high-precision wind speed and direction sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Automatic-weather-station-diagram.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Automatic weather station diagram\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Automatic-weather-station-diagram.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Automatic-weather-station-diagram-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Automatic-weather-station-diagram-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\/sonic-anemometer-high-precision-wind-speed-and-direction-sensor\">Sonic anemometer &#8211; high-precision wind speed and direction sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/es\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1334 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/blog\/everything-you-need-to-know-about-ultrasonic-wind-sensors\" aria-label=\"Everything You Need to Know About Ultrasonic Wind Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Sensors-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Wind Sensors\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Sensors-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Sensors-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Sensors-1-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\/everything-you-need-to-know-about-ultrasonic-wind-sensors\">Everything You Need to Know About Ultrasonic Wind Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/es\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1206 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/blog\/what-are-environmental-monitoring-sensors\" aria-label=\"What Are Environmental Monitoring Sensors?\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Environmental-Monitoring-Sensors.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Environmental Monitoring Sensors\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Environmental-Monitoring-Sensors.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Environmental-Monitoring-Sensors-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Environmental-Monitoring-Sensors-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\/what-are-environmental-monitoring-sensors\">What Are Environmental Monitoring Sensors?<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/es\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1371 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/blog\/the-relationship-between-rainfall-and-agriculture-and-the-role-of-rain-gauges\" aria-label=\"The Relationship Between Rainfall and Agriculture, and the Role of Rain Gauges\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"351\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Rain-Gauges-1.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Rain Gauges\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Rain-Gauges-1.jpg 750w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Rain-Gauges-1-300x140.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\/the-relationship-between-rainfall-and-agriculture-and-the-role-of-rain-gauges\">The Relationship Between Rainfall and Agriculture, and the Role of Rain Gauges<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/es\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1288 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/es\/blog\/what-is-an-anemometer-understanding-the-device-that-measures-wind\" aria-label=\"What Is an Anemometer? Understanding the Device That Measures Wind\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Anemometer-4.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Anemometer\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Anemometer-4.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Anemometer-4-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Anemometer-4-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\/what-is-an-anemometer-understanding-the-device-that-measures-wind\">What Is an Anemometer? Understanding the Device That Measures Wind<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/es\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/es\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1324_6f30d9-3b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1324_6f30d9-3b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1324_6f30d9-3b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1324_6f30d9-3b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1324_6f30d9-3b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1324_6f30d9-3b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1324_6f30d9-3b alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1324_7da2fe-6a > .kt-inside-inner-col,.kadence-column1324_7da2fe-6a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1324_7da2fe-6a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1324_7da2fe-6a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1324_7da2fe-6a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1324_7da2fe-6a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1324_7da2fe-6a{position:relative;}@media all and (max-width: 1024px){.kadence-column1324_7da2fe-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1324_7da2fe-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1324_7da2fe-6a\"><div class=\"kt-inside-inner-col\"><!-- [element-3754] --><style>.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3754_74b1c9-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3754_74b1c9-b9 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3754_4ee816-cd > .kt-inside-inner-col,.kadence-column3754_4ee816-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_4ee816-cd{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_4ee816-cd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:32px;line-height:1.1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 id=\"Contact-us\" class=\"kt-adv-heading3754_83d87b-27 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3754_83d87b-27\">Contact us<\/h2>\n\n\n\n<p>Looking for customized smart sensor solutions? Our team specializes in delivering scalable, flexible, and tailored solutions to meet your specific needs.<\/p>\n\n\n\n<p>Fill out the form now to get a personalized solution. Our experts will provide professional advice and ensure your project runs smoothly. Contact us today to start boosting efficiency!<\/p>\n\n\n<style>.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{display:flex;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col,.kadence-column3754_16f1fe-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_16f1fe-90{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_16f1fe-90 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"]{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"]{text-align:center!important;}}<\/style>\n<div class=\"kt-adv-heading3754_6acede-9b wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3754_6acede-9b\">Follow Us:<\/div>\n\n\n<style>.kt-svg-icons3754_76542c-39 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons3754_76542c-39{justify-content:flex-start;gap:20px;}@media all and (max-width: 1024px){.wp-block-kadence-icon.kt-svg-icons3754_76542c-39{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons3754_76542c-39 alignnone\"><style>.kt-svg-item-3754_c58179-25 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_c58179-25 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:20px;}.kt-svg-item-3754_c58179-25:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_c58179-25\"><a href=\"https:\/\/www.facebook.com\/ultrasonicwindspeed\/\" class=\"kt-svg-icon-link\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_facebook-n\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-3754_e1d41f-13 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_e1d41f-13 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:17px;}.kt-svg-item-3754_e1d41f-13:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_e1d41f-13\"><a href=\"https:\/\/www.yantaisensor.com\/\" class=\"kt-svg-icon-link\" aria-label=\"Twitter\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_twitterX\"><svg viewBox=\"0 0 1200 1227\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M714.163 519.284L1160.89 0H1055.03L667.137 450.887L357.328 0H0L468.492 681.821L0 1226.37H105.866L515.491 750.218L842.672 1226.37H1200L714.137 519.284H714.163ZM569.165 687.828L521.697 619.934L144.011 79.6944H306.615L611.412 515.685L658.88 583.579L1055.08 1150.3H892.476L569.165 687.854V687.828Z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-3754_12db46-e9 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_12db46-e9 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:22px;}.kt-svg-item-3754_12db46-e9:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_12db46-e9\"><a href=\"https:\/\/www.youtube.com\/@sensoryantai\" class=\"kt-svg-icon-link\" aria-label=\"YouTube\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_youtube\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3754_395d66-d2 > .kt-inside-inner-col,.kadence-column3754_395d66-d2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_395d66-d2{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_395d66-d2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column3754_530ead-5a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column3754_530ead-5a > .kt-inside-inner-col,.kadence-column3754_530ead-5a > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{column-gap:0px;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_530ead-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column3754_530ead-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_530ead-5a{text-align:left;}.kadence-column3754_530ead-5a{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_530ead-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_530ead-5a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_530ead-5a kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-select-style-field{color:var(--global-palette3, #1A202C);border-width:0px 0px 3px 0px;background:rgba(0, 0, 0, 0);border-color:var(--global-palette2, #2B6CB0);}.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-forms-submit{border-radius:50px;}.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-forms-submit{text-transform:uppercase;}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-3754_2f0a81-e6 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_0\" id=\"kb_field_3754_2f0a81-e6_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_1\" id=\"kb_field_3754_2f0a81-e6_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_2\" id=\"kb_field_3754_2f0a81-e6_2\" data-label=\"Phone\/WhatsApp\" type=\"text\" placeholder=\"Phone\/WhatsApp\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-2\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><textarea name=\"kb_field_3\" id=\"kb_field_3754_2f0a81-e6_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Message\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"3754_2f0a81-e6\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"3754\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\">Send a Message<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Activar JavaScript en tu navegador para enviar el formulario<\/div><style>.kadence-form-3754_2f0a81-e6 .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n<!-- [\/element-3754] -->\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>RY-CZS\/485 Tube&nbsp;Smart RS485 Digital Output Microphone Outdoor Noise Sensor RY-CZS\/485 Tube Smart RS485 Digital Output Microphone Outdoor Noise Sensor is a smart integrated noise sensor specifically designed for outdoor and industrial applications. Featuring a tubular stainless steel housing, it incorporates a high-sensitivity condenser microphone and digital processing circuitry to accurately detect and calculate environmental decibel&#8230;<\/p>","protected":false},"featured_media":3975,"menu_order":56,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"normal","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-1324","product","type-product","status-publish","has-post-thumbnail","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":["https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Tube-Smart-RS485-Digital-Output-Microphone-Outdoor-Noise-Sensor-7.webp",800,600,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.yantaisensor.com\/es\/wp-json\/wp\/v2\/product\/1324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yantaisensor.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.yantaisensor.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":3,"href":"https:\/\/www.yantaisensor.com\/es\/wp-json\/wp\/v2\/product\/1324\/revisions"}],"predecessor-version":[{"id":6785,"href":"https:\/\/www.yantaisensor.com\/es\/wp-json\/wp\/v2\/product\/1324\/revisions\/6785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yantaisensor.com\/es\/wp-json\/wp\/v2\/media\/3975"}],"wp:attachment":[{"href":"https:\/\/www.yantaisensor.com\/es\/wp-json\/wp\/v2\/media?parent=1324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}