{"id":3729,"date":"2025-12-18T11:06:32","date_gmt":"2025-12-18T03:06:32","guid":{"rendered":"https:\/\/www.yantaisensor.com\/?page_id=3729"},"modified":"2026-04-21T14:25:41","modified_gmt":"2026-04-21T06:25:41","slug":"agriculture-sensors-for-sale","status":"publish","type":"page","link":"https:\/\/www.yantaisensor.com\/fr\/agriculture-sensors-for-sale","title":{"rendered":"Capteurs agricoles"},"content":{"rendered":"<style>.kb-row-layout-id3729_5c7a67-2a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3729_5c7a67-2a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3729_5c7a67-2a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:100px;padding-bottom:100px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3729_5c7a67-2a{background-image:url('https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Agriculture-Sensors-.webp');background-size:cover;background-position:45% 79%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id3729_5c7a67-2a > .kt-row-layout-overlay{opacity:0.86;background-color:rgba(3, 0, 0, 0.6);}@media all and (max-width: 1024px){.kb-row-layout-id3729_5c7a67-2a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3729_5c7a67-2a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3729_5c7a67-2a alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3729_4b206c-b3 > .kt-inside-inner-col,.kadence-column3729_4b206c-b3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3729_4b206c-b3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3729_4b206c-b3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3729_4b206c-b3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3729_4b206c-b3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3729_4b206c-b3{position:relative;}@media all and (max-width: 1024px){.kadence-column3729_4b206c-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3729_4b206c-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3729_4b206c-b3 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3729_e73a9c-37, .wp-block-kadence-advancedheading.kt-adv-heading3729_e73a9c-37[data-kb-block=\"kb-adv-heading3729_e73a9c-37\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3729_e73a9c-37 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3729_e73a9c-37[data-kb-block=\"kb-adv-heading3729_e73a9c-37\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3729_e73a9c-37 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3729_e73a9c-37[data-kb-block=\"kb-adv-heading3729_e73a9c-37\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3729_e73a9c-37, .wp-block-kadence-advancedheading.kt-adv-heading3729_e73a9c-37[data-kb-block=\"kb-adv-heading3729_e73a9c-37\"]{font-size:var(--global-kb-font-size-xl, 3rem);}}<\/style>\n<h1 class=\"kt-adv-heading3729_e73a9c-37 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3729_e73a9c-37\">Agriculture Sensors<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3729_03ae54-2e, .wp-block-kadence-advancedheading.kt-adv-heading3729_03ae54-2e[data-kb-block=\"kb-adv-heading3729_03ae54-2e\"]{max-width:900px;margin-right:auto;margin-left:auto;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3729_03ae54-2e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3729_03ae54-2e[data-kb-block=\"kb-adv-heading3729_03ae54-2e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3729_03ae54-2e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3729_03ae54-2e[data-kb-block=\"kb-adv-heading3729_03ae54-2e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3729_03ae54-2e wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3729_03ae54-2e\">Yantai provides customized agriculture sensor solutions for precision farming, greenhouse monitoring, irrigation management, and environmental data collection. From soil and climate sensing to integrated monitoring systems, our team delivers tailored products and technical support to match your specific project requirements.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3729_abcd50-80 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3729_abcd50-80 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3729_abcd50-80 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3729_abcd50-80 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3729_abcd50-80 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3729_abcd50-80 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3729_abcd50-80 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3729_bdbd2e-24 > .kt-inside-inner-col,.kadence-column3729_bdbd2e-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3729_bdbd2e-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3729_bdbd2e-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3729_bdbd2e-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3729_bdbd2e-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3729_bdbd2e-24{position:relative;}@media all and (max-width: 1024px){.kadence-column3729_bdbd2e-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3729_bdbd2e-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3729_bdbd2e-24\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns3729_076d25-32, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns3729_076d25-32, .wp-block-kadence-advancedbtn.kb-btns3729_076d25-32, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns3729_076d25-32{margin-bottom:var(--global-kb-spacing-lg, 3rem);}.wp-block-kadence-advancedbtn.kb-btns3729_076d25-32{gap:var(--global-kb-gap-sm, 1rem);flex-direction:row;justify-content:center;align-items:center;}.kt-btns3729_076d25-32 .kt-button{font-weight:normal;font-style:normal;}.kt-btns3729_076d25-32 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3729_076d25-32 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3729_076d25-32 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3729_076d25-32 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3729_076d25-32 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3729_076d25-32 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3729_076d25-32 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns3729_076d25-32{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:row;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3729_076d25-32\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3729_3211d2-50.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3729_3211d2-50.kb-button{color:var(--global-palette6, #718096);background:var(--global-palette9, #ffffff);text-transform:capitalize;border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.wp-block-kadence-advancedbtn .kb-btn3729_3211d2-50.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3729_3211d2-50.kb-button:focus{color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3729_3211d2-50.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3729_3211d2-50.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><a class=\"kb-button kt-button button kb-btn3729_3211d2-50 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.yantaisensor.com\/weather-sensor-manufacturer-supplier\"><span class=\"kt-btn-inner-text\">Weather Sensor<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3729_177626-d5.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3729_177626-d5.kb-button{color:var(--global-palette6, #718096);background:var(--global-palette9, #ffffff);text-transform:capitalize;border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.wp-block-kadence-advancedbtn .kb-btn3729_177626-d5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3729_177626-d5.kb-button:focus{color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3729_177626-d5.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3729_177626-d5.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><a class=\"kb-button kt-button button kb-btn3729_177626-d5 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.yantaisensor.com\/agriculture-sensors-for-sale\"><span class=\"kt-btn-inner-text\">Agriculture Sensors<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3729_bbbdc2-b8.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3729_bbbdc2-b8.kb-button{color:var(--global-palette6, #718096);background:var(--global-palette9, #ffffff);text-transform:capitalize;border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.wp-block-kadence-advancedbtn .kb-btn3729_bbbdc2-b8.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3729_bbbdc2-b8.kb-button:focus{color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3729_bbbdc2-b8.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3729_bbbdc2-b8.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><a class=\"kb-button kt-button button kb-btn3729_bbbdc2-b8 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.yantaisensor.com\/sloar-sensors\"><span class=\"kt-btn-inner-text\">Sloar Sensors<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3729_4bab07-be.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3729_4bab07-be.kb-button{color:var(--global-palette6, #718096);background:var(--global-palette9, #ffffff);text-transform:capitalize;border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kb-btn3729_4bab07-be.kb-button .kb-svg-icon-wrap{color:var(--global-palette9, #ffffff);}.wp-block-kadence-advancedbtn .kb-btn3729_4bab07-be.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3729_4bab07-be.kb-button:focus{color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3729_4bab07-be.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3729_4bab07-be.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><a class=\"kb-button kt-button button kb-btn3729_4bab07-be kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.yantaisensor.com\/traffic-sensor-system-manufacturer\"><span class=\"kt-btn-inner-text\">Traffic Sensor<\/span><\/a><\/div>\n\n\n\n<p>Yantai offers complete agriculture sensor systems and end-to-end solutions, including soil moisture and nutrient sensors, temperature and humidity sensors, light and radiation sensors, weather stations, and data acquisition and transmission units. These devices can be flexibly integrated into intelligent monitoring platforms for precision farming, greenhouse automation, smart irrigation, and environmental management.<\/p>\n\n\n\n<p>We have extensive field tests and proven application cases, our solutions are validated under real agricultural conditions, and we have strong system integration capabilities and project experience, Yantai supports customers from solution design to deployment and optimization.<\/p>\n\n\n<style>.kt-post-loop3729_484f37-47 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop3729_484f37-47 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{text-align:center;}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{justify-content:center;}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;font-family:var( --global-heading-font-family, inherit );font-weight:inherit;font-style:normal;text-transform:capitalize;}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item .entry-title:hover{color:var(--global-palette1, #3182CE);}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop3729_484f37-47 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop3729_484f37-47 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop3729_484f37-47 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop3729_484f37-47 .entry-content:after{height:0px;}.kt-post-loop3729_484f37-47 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop3729_484f37-47 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop3729_484f37-47 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop3729_484f37-47 kt-post-grid-layout-grid \"><div class=\"kt-post-grid-layout-grid-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><article class=\"kt-blocks-post-grid-item post-3762 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/smart-temperature-sensor-in-greenhouse\" aria-label=\"Smart Temperature Sensor in Greenhouse\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/smart-temperature-sensor-6.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"smart temperature sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/smart-temperature-sensor-6.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/smart-temperature-sensor-6-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/smart-temperature-sensor-6-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/smart-temperature-sensor-in-greenhouse\">Smart Temperature Sensor in Greenhouse<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-3859 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/greenhouse-temperature-controller\" aria-label=\"Greenhouse Temperature Controller\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Greenhouse-Temperature-Controller-15.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Greenhouse Temperature Controller\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Greenhouse-Temperature-Controller-15.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Greenhouse-Temperature-Controller-15-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Greenhouse-Temperature-Controller-15-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/greenhouse-temperature-controller\">Greenhouse Temperature Controller<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-2557 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/weather-station-with-multiple-sensors\" aria-label=\"Weather Station With Multiple Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Weather-Station-With-Multiple-Sensors\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/weather-station-with-multiple-sensors\">Weather Station With Multiple Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-3977 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/leaf-surface-temperature-and-humidity-sensor\" aria-label=\"Leaf Surface Temperature and Humidity Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Leaf-Surface-Temperature-and-Humidity-6.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Leaf Surface Temperature and Humidity\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Leaf-Surface-Temperature-and-Humidity-6.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Leaf-Surface-Temperature-and-Humidity-6-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Leaf-Surface-Temperature-and-Humidity-6-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Leaf-Surface-Temperature-and-Humidity-6-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/leaf-surface-temperature-and-humidity-sensor\">Leaf Surface Temperature and Humidity Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4050 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/soil-temperature-and-humidity-integrated-sensor\" aria-label=\"Soil Temperature and Humidity Integrated Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Soil-temperature-and-humidity-integrated-sensor-24.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Soil temperature and humidity integrated sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Soil-temperature-and-humidity-integrated-sensor-24.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Soil-temperature-and-humidity-integrated-sensor-24-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Soil-temperature-and-humidity-integrated-sensor-24-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Soil-temperature-and-humidity-integrated-sensor-24-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/soil-temperature-and-humidity-integrated-sensor\">Soil Temperature and Humidity Integrated Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4107 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/tubular-soil-monitoring-instrument\" aria-label=\"Tubular Soil Monitoring Instrument\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Tubular-soil-monitoring-instrument-19.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Tubular soil monitoring instrument\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Tubular-soil-monitoring-instrument-19.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Tubular-soil-monitoring-instrument-19-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Tubular-soil-monitoring-instrument-19-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Tubular-soil-monitoring-instrument-19-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/tubular-soil-monitoring-instrument\">Tubular Soil Monitoring Instrument<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4229 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/ry-cgh-photosynthetic-radiation-sensor\" aria-label=\"RY-CGH Photosynthetic Radiation Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/photosynthetic-radiation-sensor-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"photosynthetic radiation sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/photosynthetic-radiation-sensor-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/photosynthetic-radiation-sensor-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/photosynthetic-radiation-sensor-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/photosynthetic-radiation-sensor-1-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/ry-cgh-photosynthetic-radiation-sensor\">RY-CGH Photosynthetic Radiation Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5146 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/meteorological-sensor\" aria-label=\"XF600 Integrated Meteorological Sensor for Smart Agriculture &amp; IoT(XF600)\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF600 Meteorological Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/meteorological-sensor\">XF600 Integrated Meteorological Sensor for Smart Agriculture &amp; IoT(XF600)<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4313 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/ry-fsx-integrated-wind-speed-direction-sensor-for-weather-station\" aria-label=\"RY-FSX Integrated Wind Speed Direction Sensor For Weather Station\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"integrated wind speed and direction sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/ry-fsx-integrated-wind-speed-direction-sensor-for-weather-station\">RY-FSX Integrated Wind Speed Direction Sensor For Weather Station<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6115 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/temperature-humidity-pressure-sensor\" aria-label=\"Temperature Humidity Pressure Sensor Manufacturer for Weather Monitoring\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Temperature-Humidity-Pressure-Sensor-3.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Temperature Humidity Pressure Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Temperature-Humidity-Pressure-Sensor-3.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Temperature-Humidity-Pressure-Sensor-3-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Temperature-Humidity-Pressure-Sensor-3-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Temperature-Humidity-Pressure-Sensor-3-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/temperature-humidity-pressure-sensor\">Temperature Humidity Pressure Sensor Manufacturer for Weather Monitoring<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4268 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/ry-ylx-tipping-bucket-rain-sensor\" aria-label=\"RY-YLX Tipping Bucket Rain Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Tipping Bucket Rain Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/ry-ylx-tipping-bucket-rain-sensor\">RY-YLX Tipping Bucket Rain Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4158 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/ry-cyx-rain-and-snow-sensor\" aria-label=\"RY-CYX Rain And Snow Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"rain and snow sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/ry-cyx-rain-and-snow-sensor\">RY-CYX Rain And Snow Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6208 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/water-quality-sensor\" aria-label=\"Digital Water Quality Sensor for Water Monitoring\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Water-Quality-Sensor.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Water Quality Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Water-Quality-Sensor.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Water-Quality-Sensor-300x300.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Water-Quality-Sensor-150x150.webp 150w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Water-Quality-Sensor-768x768.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/Water-Quality-Sensor-12x12.webp 12w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/water-quality-sensor\">Digital Water Quality Sensor for Water Monitoring<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6271 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/fr\/product\/water-quality-monitoring-station\" aria-label=\"Water Quality Monitoring Station for Environmental Protection\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/water-quality-monitoring-station-11.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"water quality monitoring station\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/water-quality-monitoring-station-11.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/water-quality-monitoring-station-11-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/water-quality-monitoring-station-11-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/water-quality-monitoring-station-11-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/fr\/product\/water-quality-monitoring-station\">Water Quality Monitoring Station for Environmental Protection<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<!-- [element-3754] --><style>.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3754_74b1c9-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3754_74b1c9-b9 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3754_4ee816-cd > .kt-inside-inner-col,.kadence-column3754_4ee816-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_4ee816-cd{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_4ee816-cd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:32px;line-height:1.1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 id=\"Contact-us\" class=\"kt-adv-heading3754_83d87b-27 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3754_83d87b-27\">Contact us<\/h2>\n\n\n\n<p>Looking for customized smart sensor solutions? Our team specializes in delivering scalable, flexible, and tailored solutions to meet your specific needs.<\/p>\n\n\n\n<p>Fill out the form now to get a personalized solution. Our experts will provide professional advice and ensure your project runs smoothly. Contact us today to start boosting efficiency!<\/p>\n\n\n<style>.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{display:flex;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col,.kadence-column3754_16f1fe-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_16f1fe-90{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_16f1fe-90 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"]{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"]{text-align:center!important;}}<\/style>\n<div class=\"kt-adv-heading3754_6acede-9b wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3754_6acede-9b\">Follow Us:<\/div>\n\n\n<style>.kt-svg-icons3754_76542c-39 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons3754_76542c-39{justify-content:flex-start;gap:20px;}@media all and (max-width: 1024px){.wp-block-kadence-icon.kt-svg-icons3754_76542c-39{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons3754_76542c-39 alignnone\"><style>.kt-svg-item-3754_c58179-25 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_c58179-25 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:20px;}.kt-svg-item-3754_c58179-25:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_c58179-25\"><a href=\"https:\/\/www.facebook.com\/ultrasonicwindspeed\/\" class=\"kt-svg-icon-link\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_facebook-n\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-3754_e1d41f-13 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_e1d41f-13 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:17px;}.kt-svg-item-3754_e1d41f-13:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_e1d41f-13\"><a href=\"https:\/\/www.yantaisensor.com\/\" class=\"kt-svg-icon-link\" aria-label=\"Twitter\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_twitterX\"><svg viewBox=\"0 0 1200 1227\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M714.163 519.284L1160.89 0H1055.03L667.137 450.887L357.328 0H0L468.492 681.821L0 1226.37H105.866L515.491 750.218L842.672 1226.37H1200L714.137 519.284H714.163ZM569.165 687.828L521.697 619.934L144.011 79.6944H306.615L611.412 515.685L658.88 583.579L1055.08 1150.3H892.476L569.165 687.854V687.828Z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-3754_12db46-e9 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_12db46-e9 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:22px;}.kt-svg-item-3754_12db46-e9:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_12db46-e9\"><a href=\"https:\/\/www.youtube.com\/@sensoryantai\" class=\"kt-svg-icon-link\" aria-label=\"YouTube\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_youtube\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3754_395d66-d2 > .kt-inside-inner-col,.kadence-column3754_395d66-d2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_395d66-d2{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_395d66-d2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column3754_530ead-5a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column3754_530ead-5a > .kt-inside-inner-col,.kadence-column3754_530ead-5a > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{column-gap:0px;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_530ead-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column3754_530ead-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_530ead-5a{text-align:left;}.kadence-column3754_530ead-5a{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_530ead-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_530ead-5a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_530ead-5a kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-select-style-field{color:var(--global-palette3, #1A202C);border-width:0px 0px 3px 0px;background:rgba(0, 0, 0, 0);border-color:var(--global-palette2, #2B6CB0);}.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-forms-submit{border-radius:50px;}.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-forms-submit{text-transform:uppercase;}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-3754_2f0a81-e6 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_0\" id=\"kb_field_3754_2f0a81-e6_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_1\" id=\"kb_field_3754_2f0a81-e6_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_2\" id=\"kb_field_3754_2f0a81-e6_2\" data-label=\"Phone\/WhatsApp\" type=\"text\" placeholder=\"Phone\/WhatsApp\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-2\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><textarea name=\"kb_field_3\" id=\"kb_field_3754_2f0a81-e6_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Message\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"3754_2f0a81-e6\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"3754\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\">Send a Message<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Veuillez activer JavaScript dans votre navigateur pour envoyer le formulaire.<\/div><style>.kadence-form-3754_2f0a81-e6 .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n<!-- [\/element-3754] -->\n","protected":false},"excerpt":{"rendered":"<p>Agriculture Sensors Yantai provides customized agriculture sensor solutions for precision farming, greenhouse monitoring, irrigation management, and environmental data collection. From soil and climate sensing to integrated monitoring systems, our team delivers tailored products and technical support to match your specific project requirements. Yantai offers complete agriculture sensor systems and end-to-end solutions, including soil moisture and&#8230;<\/p>","protected":false},"author":1,"featured_media":3731,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":true,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-3729","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":["https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Agriculture-Sensors--1024x348.webp",1024,348,true],"author_info":{"display_name":"admin","author_link":"https:\/\/www.yantaisensor.com\/fr\/author\/admin"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.yantaisensor.com\/fr\/wp-json\/wp\/v2\/pages\/3729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yantaisensor.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.yantaisensor.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.yantaisensor.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yantaisensor.com\/fr\/wp-json\/wp\/v2\/comments?post=3729"}],"version-history":[{"count":12,"href":"https:\/\/www.yantaisensor.com\/fr\/wp-json\/wp\/v2\/pages\/3729\/revisions"}],"predecessor-version":[{"id":6359,"href":"https:\/\/www.yantaisensor.com\/fr\/wp-json\/wp\/v2\/pages\/3729\/revisions\/6359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yantaisensor.com\/fr\/wp-json\/wp\/v2\/media\/3731"}],"wp:attachment":[{"href":"https:\/\/www.yantaisensor.com\/fr\/wp-json\/wp\/v2\/media?parent=3729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}