{"id":3700,"date":"2025-12-17T16:49:39","date_gmt":"2025-12-17T08:49:39","guid":{"rendered":"https:\/\/www.yantaisensor.com\/?page_id=3700"},"modified":"2026-04-08T09:42:12","modified_gmt":"2026-04-08T01:42:12","slug":"%d0%b4%d0%b0%d1%82%d1%87%d0%b8%d0%ba-%d0%bf%d0%be%d0%b3%d0%be%d0%b4%d1%8b-%d0%bf%d1%80%d0%be%d0%b8%d0%b7%d0%b2%d0%be%d0%b4%d0%b8%d1%82%d0%b5%d0%bb%d1%8c-%d0%bf%d0%be%d1%81%d1%82%d0%b0%d0%b2%d1%89","status":"publish","type":"page","link":"https:\/\/www.yantaisensor.com\/ru\/weather-sensor-manufacturer-supplier","title":{"rendered":"\u0414\u0430\u0442\u0447\u0438\u043a \u043f\u043e\u0433\u043e\u0434\u044b"},"content":{"rendered":"<style>.kb-row-layout-id3700_ffd359-dd > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3700_ffd359-dd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3700_ffd359-dd > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:100px;padding-bottom:100px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3700_ffd359-dd{background-image:url('https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Weather-Monitoring-Solutions22.webp');background-size:cover;background-position:61% 34%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id3700_ffd359-dd > .kt-row-layout-overlay{opacity:0.86;background-color:rgba(3, 0, 0, 0.6);}@media all and (max-width: 1024px){.kb-row-layout-id3700_ffd359-dd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3700_ffd359-dd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3700_ffd359-dd alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3700_e08208-0a > .kt-inside-inner-col,.kadence-column3700_e08208-0a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3700_e08208-0a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3700_e08208-0a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3700_e08208-0a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3700_e08208-0a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3700_e08208-0a{position:relative;}@media all and (max-width: 1024px){.kadence-column3700_e08208-0a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3700_e08208-0a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3700_e08208-0a inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3700_70bd32-ae, .wp-block-kadence-advancedheading.kt-adv-heading3700_70bd32-ae[data-kb-block=\"kb-adv-heading3700_70bd32-ae\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3700_70bd32-ae mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3700_70bd32-ae[data-kb-block=\"kb-adv-heading3700_70bd32-ae\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3700_70bd32-ae img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3700_70bd32-ae[data-kb-block=\"kb-adv-heading3700_70bd32-ae\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3700_70bd32-ae, .wp-block-kadence-advancedheading.kt-adv-heading3700_70bd32-ae[data-kb-block=\"kb-adv-heading3700_70bd32-ae\"]{font-size:var(--global-kb-font-size-xl, 3rem);}}<\/style>\n<h1 class=\"kt-adv-heading3700_70bd32-ae wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3700_70bd32-ae\">Weather Sensor<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3700_cfc8a6-41, .wp-block-kadence-advancedheading.kt-adv-heading3700_cfc8a6-41[data-kb-block=\"kb-adv-heading3700_cfc8a6-41\"]{max-width:750px;margin-right:auto;margin-left:auto;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3700_cfc8a6-41 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3700_cfc8a6-41[data-kb-block=\"kb-adv-heading3700_cfc8a6-41\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3700_cfc8a6-41 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3700_cfc8a6-41[data-kb-block=\"kb-adv-heading3700_cfc8a6-41\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3700_cfc8a6-41 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3700_cfc8a6-41\">Weather sensors are used to measure and monitor environmental meteorological data such as temperature, humidity, wind speed, wind direction, atmospheric pressure, and precipitation. They are widely used in weather stations, agriculture, and environmental monitoring.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3700_2825fc-b4 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3700_2825fc-b4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3700_2825fc-b4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3700_2825fc-b4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3700_2825fc-b4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3700_2825fc-b4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3700_2825fc-b4 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3700_a2aafd-e8 > .kt-inside-inner-col,.kadence-column3700_a2aafd-e8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3700_a2aafd-e8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3700_a2aafd-e8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3700_a2aafd-e8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3700_a2aafd-e8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3700_a2aafd-e8{position:relative;}@media all and (max-width: 1024px){.kadence-column3700_a2aafd-e8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3700_a2aafd-e8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3700_a2aafd-e8\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns3700_cc83d4-8f, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns3700_cc83d4-8f, .wp-block-kadence-advancedbtn.kb-btns3700_cc83d4-8f, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns3700_cc83d4-8f{margin-bottom:var(--global-kb-spacing-lg, 3rem);}.wp-block-kadence-advancedbtn.kb-btns3700_cc83d4-8f{gap:var(--global-kb-gap-sm, 1rem);flex-direction:row;justify-content:center;align-items:center;}.kt-btns3700_cc83d4-8f .kt-button{font-weight:normal;font-style:normal;}.kt-btns3700_cc83d4-8f .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3700_cc83d4-8f .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3700_cc83d4-8f .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3700_cc83d4-8f .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3700_cc83d4-8f .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3700_cc83d4-8f .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3700_cc83d4-8f .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns3700_cc83d4-8f{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:row;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3700_cc83d4-8f\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3700_5a6cfb-f5.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3700_5a6cfb-f5.kb-button{color:var(--global-palette2, #2B6CB0);background:var(--global-palette9, #ffffff);text-transform:capitalize;border-top:1px solid var(--global-palette2, #2B6CB0);border-right:1px solid var(--global-palette2, #2B6CB0);border-bottom:1px solid var(--global-palette2, #2B6CB0);border-left:1px solid var(--global-palette2, #2B6CB0);}.wp-block-kadence-advancedbtn .kb-btn3700_5a6cfb-f5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3700_5a6cfb-f5.kb-button:focus{color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3700_5a6cfb-f5.kb-button{border-top:1px solid var(--global-palette2, #2B6CB0);border-right:1px solid var(--global-palette2, #2B6CB0);border-bottom:1px solid var(--global-palette2, #2B6CB0);border-left:1px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3700_5a6cfb-f5.kb-button{border-top:1px solid var(--global-palette2, #2B6CB0);border-right:1px solid var(--global-palette2, #2B6CB0);border-bottom:1px solid var(--global-palette2, #2B6CB0);border-left:1px solid var(--global-palette2, #2B6CB0);}}<\/style><a class=\"kb-button kt-button button kb-btn3700_5a6cfb-f5 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.yantaisensor.com\/weather-sensor-manufacturer-supplier\"><span class=\"kt-btn-inner-text\">Weather Sensor<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3700_0f143c-52.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3700_0f143c-52.kb-button{color:var(--global-palette6, #718096);background:var(--global-palette9, #ffffff);text-transform:capitalize;border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.wp-block-kadence-advancedbtn .kb-btn3700_0f143c-52.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3700_0f143c-52.kb-button:focus{color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3700_0f143c-52.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3700_0f143c-52.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><a class=\"kb-button kt-button button kb-btn3700_0f143c-52 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.yantaisensor.com\/agriculture-sensors-for-sale\"><span class=\"kt-btn-inner-text\">Agriculture Sensors<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3700_1b4b6e-ec.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3700_1b4b6e-ec.kb-button{color:var(--global-palette6, #718096);background:var(--global-palette9, #ffffff);text-transform:capitalize;border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.wp-block-kadence-advancedbtn .kb-btn3700_1b4b6e-ec.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3700_1b4b6e-ec.kb-button:focus{color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3700_1b4b6e-ec.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3700_1b4b6e-ec.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><a class=\"kb-button kt-button button kb-btn3700_1b4b6e-ec kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.yantaisensor.com\/sloar-sensors\"><span class=\"kt-btn-inner-text\">Sloar Sensors<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3700_27fe06-c9.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3700_27fe06-c9.kb-button{color:var(--global-palette6, #718096);background:var(--global-palette9, #ffffff);text-transform:capitalize;border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kb-btn3700_27fe06-c9.kb-button .kb-svg-icon-wrap{color:var(--global-palette9, #ffffff);}.wp-block-kadence-advancedbtn .kb-btn3700_27fe06-c9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3700_27fe06-c9.kb-button:focus{color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3700_27fe06-c9.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3700_27fe06-c9.kb-button{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><a class=\"kb-button kt-button button kb-btn3700_27fe06-c9 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.yantaisensor.com\/traffic-sensor-system-manufacturer\"><span class=\"kt-btn-inner-text\">Traffic Sensor<\/span><\/a><\/div>\n\n\n\n<p>As a professional meteorological sensor manufacturer, we have an experienced team that can provide customized services to meet your needs and help you achieve precise weather monitoring solutions. Whether it&#8217;s conventional parameters such as temperature, humidity, and wind speed, or complex environmental monitoring, we can tailor a solution specifically for you. <\/p>\n\n\n\n<p>Contact us to discuss how we can provide efficient and reliable solutions for your project!<\/p>\n\n\n<style>.kt-post-loop3700_92d9bb-4c .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop3700_92d9bb-4c .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{text-align:center;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item .kt-blocks-post-top-meta{justify-content:center;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;font-family:var( --global-heading-font-family, inherit );font-weight:inherit;font-style:normal;text-transform:capitalize;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item .entry-title:hover{color:var(--global-palette1, #3182CE);}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop3700_92d9bb-4c .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop3700_92d9bb-4c .entry-content:after{height:0px;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-footer a{color:#777777;}.kt-post-loop3700_92d9bb-4c .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop3700_92d9bb-4c .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop3700_92d9bb-4c kt-post-grid-layout-grid \"><div class=\"kt-post-grid-layout-grid-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><article class=\"kt-blocks-post-grid-item post-2557 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/weather-station-with-multiple-sensors\" aria-label=\"Weather Station With Multiple Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Weather-Station-With-Multiple-Sensors\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/weather-station-with-multiple-sensors\">Weather Station With Multiple Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-1382 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/portable-weather-station-automatic\" aria-label=\"RYQ-2 Portable Weather Station Automatic\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Portable Weather Station Automatic\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7-300x300.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7-150x150.webp 150w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7-768x768.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/portable-weather-station-automatic\">RYQ-2 Portable Weather Station Automatic<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4487 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/temperature-humidity-pressure-sensor-for-weather-stations\" aria-label=\"XF103 Temperature Humidity Pressure Sensor for Weather Stations\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Temperature-Humidity-Pressure-Sensor-7.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Temperature Humidity Pressure Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Temperature-Humidity-Pressure-Sensor-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Temperature-Humidity-Pressure-Sensor-7-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Temperature-Humidity-Pressure-Sensor-7-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Temperature-Humidity-Pressure-Sensor-7-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/temperature-humidity-pressure-sensor-for-weather-stations\">XF103 Temperature Humidity Pressure Sensor for Weather Stations<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-1388 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200l-ultrasonic-anemometer-sensor\" aria-label=\"XF200L Ultrasonic Anemometer Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF200L Ultrasonic Anemometer\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200l-ultrasonic-anemometer-sensor\">XF200L Ultrasonic Anemometer Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-1403 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200as-ultrasonic-anemometer\" aria-label=\"XF200AS Ultrasonic Anemometer\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF200AS Ultrasonic Anemometer\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200as-ultrasonic-anemometer\">XF200AS Ultrasonic Anemometer<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4522 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200a-ultrasonic-wind-speed-and-direction-sensor\" aria-label=\"XF200A Ultrasonic Wind Speed And Direction Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/ultrasonic-wind-speed-and-direction-sensor-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"ultrasonic wind speed and direction sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/ultrasonic-wind-speed-and-direction-sensor-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/ultrasonic-wind-speed-and-direction-sensor-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/ultrasonic-wind-speed-and-direction-sensor-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/ultrasonic-wind-speed-and-direction-sensor-1-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200a-ultrasonic-wind-speed-and-direction-sensor\">XF200A Ultrasonic Wind Speed And Direction Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4620 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf500-compact-weather-stations\" aria-label=\"xf500 Series Industrial Compact Weather Stations\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/XF500S.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF500S\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/XF500S.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/XF500S-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/XF500S-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/XF500S-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf500-compact-weather-stations\">xf500 Series Industrial Compact Weather Stations<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-1458 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf600a-compact-weather-sensor\" aria-label=\"XF600A temperature Relative humidity Rainfall wind speed direction compact weather sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF600A-compact-weather-sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF600A-compact-weather-sensor.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf600a-compact-weather-sensor\">XF600A temperature Relative humidity Rainfall wind speed direction compact weather sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4867 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/handheld-portable-weather-sensor\" aria-label=\"XF600H Handheld Portable Weather Sensor with Wind, Pressure &amp; Rainfall Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/portable-weather-sensor-20.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"portable weather sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/portable-weather-sensor-20.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/portable-weather-sensor-20-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/portable-weather-sensor-20-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/portable-weather-sensor-20-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/handheld-portable-weather-sensor\">XF600H Handheld Portable Weather Sensor with Wind, Pressure &amp; Rainfall Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-1373 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf500s-cwb-photovoltaic-power-station-compact-weather-sensor-wireless-solar-radiation-sensor\" aria-label=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf500s-cwb-photovoltaic-power-station-compact-weather-sensor-wireless-solar-radiation-sensor\">XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4586 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf400-compact-weather-station-with-rainfall-sensor\" aria-label=\"XF400 Compact Weather Station with Temperature, Humidity, Pressure &amp; Optical Rainfall Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/compact-weather-station-with-rainfall-sensor-5.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"compact weather station with rainfall sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/compact-weather-station-with-rainfall-sensor-5.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/compact-weather-station-with-rainfall-sensor-5-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/compact-weather-station-with-rainfall-sensor-5-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/compact-weather-station-with-rainfall-sensor-5-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf400-compact-weather-station-with-rainfall-sensor\">XF400 Compact Weather Station with Temperature, Humidity, Pressure &amp; Optical Rainfall Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5102 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/all-in-one-weather-station\" aria-label=\"XF700 All-in-One Weather Station withRainfall, Wind &amp; Light Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700-All-in-One-Weather-Station-8.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF700 All-in-One Weather Station\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700-All-in-One-Weather-Station-8.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700-All-in-One-Weather-Station-8-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700-All-in-One-Weather-Station-8-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700-All-in-One-Weather-Station-8-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/all-in-one-weather-station\">XF700 All-in-One Weather Station withRainfall, Wind &amp; Light Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5143 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/automatic-weather-station-with-piezo-rainfall-sensor\" aria-label=\"XF700A Automatic Weather Station with Piezo Rainfall Sensor &amp; Light Measurement\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Automatic-Weather-Station-with-Piezo-Rainfall-Sensor-3.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Automatic Weather Station with Piezo Rainfall Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Automatic-Weather-Station-with-Piezo-Rainfall-Sensor-3.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Automatic-Weather-Station-with-Piezo-Rainfall-Sensor-3-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Automatic-Weather-Station-with-Piezo-Rainfall-Sensor-3-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Automatic-Weather-Station-with-Piezo-Rainfall-Sensor-3-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/automatic-weather-station-with-piezo-rainfall-sensor\">XF700A Automatic Weather Station with Piezo Rainfall Sensor &amp; Light Measurement<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5314 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/solar-radiation-weather-station\" aria-label=\"XF700SL Compact Solar Radiation Weather Station with Rainfall &amp; Wind Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700SL-solar-radiation-weather-station-7.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF700SL solar radiation weather station\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700SL-solar-radiation-weather-station-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700SL-solar-radiation-weather-station-7-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700SL-solar-radiation-weather-station-7-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF700SL-solar-radiation-weather-station-7-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/solar-radiation-weather-station\">XF700SL Compact Solar Radiation Weather Station with Rainfall &amp; Wind Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5344 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/compact-weather-station-for-industrial-monitoring\" aria-label=\"XF700L Compact Weather Station for Industrial Monitoring with Advanced Wind Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-8.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"compact-smart-weather-station\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-8.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-8-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-8-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-8-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/compact-weather-station-for-industrial-monitoring\">XF700L Compact Weather Station for Industrial Monitoring with Advanced Wind Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5492 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/mini-weather-station\" aria-label=\"XF700S Mini Weather Station with Rainfall, Wind &amp; Solar Radiation Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF700S-Mini-Weather-Station-7.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF700S-Mini-Weather-Station\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF700S-Mini-Weather-Station-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF700S-Mini-Weather-Station-7-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF700S-Mini-Weather-Station-7-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF700S-Mini-Weather-Station-7-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/mini-weather-station\">XF700S Mini Weather Station with Rainfall, Wind &amp; Solar Radiation Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5146 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/meteorological-sensor\" aria-label=\"XF600 Integrated Meteorological Sensor for Smart Agriculture &amp; IoT(XF600)\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF600 Meteorological Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/XF600-Meteorological-Sensor-7-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/meteorological-sensor\">XF600 Integrated Meteorological Sensor for Smart Agriculture &amp; IoT(XF600)<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5449 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/ultrasonic-weather-sensor\" aria-label=\"XF600AL 6-in-1 Ultrasonic Weather Sensor (Gen 3 Wind &amp; Piezo Rain)\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF600AL-6-in-1-ultrasonic-weather-sensor-15.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF600AL 6-in-1 ultrasonic weather sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF600AL-6-in-1-ultrasonic-weather-sensor-15.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF600AL-6-in-1-ultrasonic-weather-sensor-15-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF600AL-6-in-1-ultrasonic-weather-sensor-15-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF600AL-6-in-1-ultrasonic-weather-sensor-15-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/ultrasonic-weather-sensor\">XF600AL 6-in-1 Ultrasonic Weather Sensor (Gen 3 Wind &amp; Piezo Rain)<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5372 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/best-outdoor-air-quality-sensor\" aria-label=\"XF603 Best Outdoor Air Quality Sensor For Smart City &amp; Traffic (Xf603) | Pm2.5 Pm10 Noise Light\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF603-best-outdoor-air-quality-sensor\u200b-7.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF603 best outdoor air quality sensor\u200b\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF603-best-outdoor-air-quality-sensor\u200b-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF603-best-outdoor-air-quality-sensor\u200b-7-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF603-best-outdoor-air-quality-sensor\u200b-7-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/XF603-best-outdoor-air-quality-sensor\u200b-7-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/best-outdoor-air-quality-sensor\">XF603 Best Outdoor Air Quality Sensor For Smart City &amp; Traffic (Xf603) | Pm2.5 Pm10 Noise Light<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5232 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/compact-smart-weather-station\" aria-label=\"XF600L Compact Smart Weather Station\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-6.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"compact-smart-weather-station\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-6.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-6-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-6-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/compact-smart-weather-station-6-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/compact-smart-weather-station\">XF600L Compact Smart Weather Station<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4646 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/ry-cyx-capacitive-rain-sensor\" aria-label=\"Capacitive Rain Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"rain and snow sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/rain-and-snow-sensor-1-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/ry-cyx-capacitive-rain-sensor\">Capacitive Rain Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4436 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/optical-rain-sensor\" aria-label=\"XF100A Optical Rain Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/optical-rain-sensor-21.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"optical rain sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/optical-rain-sensor-21.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/optical-rain-sensor-21-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/optical-rain-sensor-21-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/optical-rain-sensor-21-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/optical-rain-sensor\">XF100A Optical Rain Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4384 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf100-piezoelectric-rain-gauge\" aria-label=\"XF100 Piezoelectric Rain Gauge\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/piezoelectric-rain-gauge-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"piezoelectric rain gauge\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/piezoelectric-rain-gauge-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/piezoelectric-rain-gauge-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/piezoelectric-rain-gauge-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/piezoelectric-rain-gauge-1-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf100-piezoelectric-rain-gauge\">XF100 Piezoelectric Rain Gauge<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5386 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/compact-multi-weather-sensor\" aria-label=\"Compact Multi Weather Sensor XF800\/800L\/900\/1013\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Compact-Multi-Weather-Sensor-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Compact Multi Weather Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Compact-Multi-Weather-Sensor-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Compact-Multi-Weather-Sensor-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Compact-Multi-Weather-Sensor-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Compact-Multi-Weather-Sensor-16x12.webp 16w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/02\/Compact-Multi-Weather-Sensor.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/compact-multi-weather-sensor\">Compact Multi Weather Sensor XF800\/800L\/900\/1013<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5803 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/air-quality-outdoor-sensor\" aria-label=\"Air Quality Outdoor Sensor for Environmental Monitoring\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/air-quality-outdoor-sensor\u200b-3.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"air-quality-outdoor-sensor\u200b\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/air-quality-outdoor-sensor\u200b-3.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/air-quality-outdoor-sensor\u200b-3-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/air-quality-outdoor-sensor\u200b-3-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/air-quality-outdoor-sensor\u200b-3-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/air-quality-outdoor-sensor\">Air Quality Outdoor Sensor for Environmental Monitoring<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4958 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/optical-rain-gauge-for-weather-station\" aria-label=\"RG-11 Optical Rain Gauge for weather station\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Optical-Rain-Gauge-4.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Optical Rain Gauge\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Optical-Rain-Gauge-4.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Optical-Rain-Gauge-4-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Optical-Rain-Gauge-4-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Optical-Rain-Gauge-4-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/optical-rain-gauge-for-weather-station\">RG-11 Optical Rain Gauge for weather station<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6006 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/micro-weather-sensor\" aria-label=\"Micro Weather Sensor for Precise Environmental Monitoring\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/HCD6820.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"micro weather sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/HCD6820.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/HCD6820-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/HCD6820-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/04\/HCD6820-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/micro-weather-sensor\">Micro Weather Sensor for Precise Environmental Monitoring<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4268 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/ry-ylx-tipping-bucket-rain-sensor\" aria-label=\"RY-YLX Tipping Bucket Rain Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Tipping Bucket Rain Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/Tipping-Bucket-Rain-Sensor-1-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/ry-ylx-tipping-bucket-rain-sensor\">RY-YLX Tipping Bucket Rain Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4313 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/ry-fsx-integrated-wind-speed-direction-sensor-for-weather-station\" aria-label=\"RY-FSX Integrated Wind Speed Direction Sensor For Weather Station\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"integrated wind speed and direction sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/01\/integrated-wind-speed-and-direction-sensor-3-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/ry-fsx-integrated-wind-speed-direction-sensor-for-weather-station\">RY-FSX Integrated Wind Speed Direction Sensor For Weather Station<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5611 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/wind-speed-sensor-outdoor\" aria-label=\"RY-FX01-X Wind Speed Sensor Outdoor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-speed-sensor-outdoor-9.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"wind-speed-sensor-outdoor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-speed-sensor-outdoor-9.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-speed-sensor-outdoor-9-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-speed-sensor-outdoor-9-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-speed-sensor-outdoor-9-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/wind-speed-sensor-outdoor\">RY-FX01-X Wind Speed Sensor Outdoor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5573 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/marine-automatic-weather-station\" aria-label=\"XFC2-2 Marine Automatic Weather Station\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/marine-automatic-weather-station2.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"marine-automatic-weather-station\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/marine-automatic-weather-station2.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/marine-automatic-weather-station2-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/marine-automatic-weather-station2-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/marine-automatic-weather-station2-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/marine-automatic-weather-station\">XFC2-2 Marine Automatic Weather Station<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-5612 product type-product status-publish has-post-thumbnail hentry\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/wind-direction-sensor\" aria-label=\"RY-FX02-X-485 Wind Direction Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-direction-sensor-2.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"wind-direction-sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-direction-sensor-2.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-direction-sensor-2-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-direction-sensor-2-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/03\/wind-direction-sensor-2-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/wind-direction-sensor\">RY-FX02-X-485 Wind Direction Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<!-- [element-3754] --><style>.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3754_74b1c9-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3754_74b1c9-b9 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3754_4ee816-cd > .kt-inside-inner-col,.kadence-column3754_4ee816-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_4ee816-cd{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_4ee816-cd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:32px;line-height:1.1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 id=\"Contact-us\" class=\"kt-adv-heading3754_83d87b-27 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3754_83d87b-27\">Contact us<\/h2>\n\n\n\n<p>Looking for customized smart sensor solutions? Our team specializes in delivering scalable, flexible, and tailored solutions to meet your specific needs.<\/p>\n\n\n\n<p>Fill out the form now to get a personalized solution. Our experts will provide professional advice and ensure your project runs smoothly. Contact us today to start boosting efficiency!<\/p>\n\n\n<style>.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{display:flex;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col,.kadence-column3754_16f1fe-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_16f1fe-90{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_16f1fe-90 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"]{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"]{text-align:center!important;}}<\/style>\n<div class=\"kt-adv-heading3754_6acede-9b wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3754_6acede-9b\">Follow Us:<\/div>\n\n\n<style>.kt-svg-icons3754_76542c-39 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons3754_76542c-39{justify-content:flex-start;gap:20px;}@media all and (max-width: 1024px){.wp-block-kadence-icon.kt-svg-icons3754_76542c-39{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons3754_76542c-39 alignnone\"><style>.kt-svg-item-3754_c58179-25 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_c58179-25 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:20px;}.kt-svg-item-3754_c58179-25:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_c58179-25\"><a href=\"https:\/\/www.facebook.com\/ultrasonicwindspeed\/\" class=\"kt-svg-icon-link\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_facebook-n\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-3754_e1d41f-13 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_e1d41f-13 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:17px;}.kt-svg-item-3754_e1d41f-13:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_e1d41f-13\"><a href=\"https:\/\/www.yantaisensor.com\/\" class=\"kt-svg-icon-link\" aria-label=\"Twitter\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_twitterX\"><svg viewBox=\"0 0 1200 1227\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M714.163 519.284L1160.89 0H1055.03L667.137 450.887L357.328 0H0L468.492 681.821L0 1226.37H105.866L515.491 750.218L842.672 1226.37H1200L714.137 519.284H714.163ZM569.165 687.828L521.697 619.934L144.011 79.6944H306.615L611.412 515.685L658.88 583.579L1055.08 1150.3H892.476L569.165 687.854V687.828Z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-3754_12db46-e9 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_12db46-e9 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:22px;}.kt-svg-item-3754_12db46-e9:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_12db46-e9\"><a href=\"https:\/\/www.youtube.com\/@sensoryantai\" class=\"kt-svg-icon-link\" aria-label=\"YouTube\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_youtube\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3754_395d66-d2 > .kt-inside-inner-col,.kadence-column3754_395d66-d2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_395d66-d2{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_395d66-d2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column3754_530ead-5a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column3754_530ead-5a > .kt-inside-inner-col,.kadence-column3754_530ead-5a > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{column-gap:0px;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_530ead-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column3754_530ead-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_530ead-5a{text-align:left;}.kadence-column3754_530ead-5a{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_530ead-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_530ead-5a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_530ead-5a kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-select-style-field{color:var(--global-palette3, #1A202C);border-width:0px 0px 3px 0px;background:rgba(0, 0, 0, 0);border-color:var(--global-palette2, #2B6CB0);}.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-forms-submit{border-radius:50px;}.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-forms-submit{text-transform:uppercase;}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-3754_2f0a81-e6 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_0\" id=\"kb_field_3754_2f0a81-e6_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_1\" id=\"kb_field_3754_2f0a81-e6_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_2\" id=\"kb_field_3754_2f0a81-e6_2\" data-label=\"Phone\/WhatsApp\" type=\"text\" placeholder=\"Phone\/WhatsApp\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-2\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><textarea name=\"kb_field_3\" id=\"kb_field_3754_2f0a81-e6_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Message\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"3754_2f0a81-e6\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"3754\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\">Send a Message<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">\u041f\u043e\u0436\u0430\u043b\u0443\u0439\u0441\u0442\u0430, \u0432\u043a\u043b\u044e\u0447\u0438\u0442\u0435 JavaScript \u0432 \u0432\u0430\u0448\u0435\u043c \u0431\u0440\u0430\u0443\u0437\u0435\u0440\u0435, \u0447\u0442\u043e\u0431\u044b \u043e\u0442\u043f\u0440\u0430\u0432\u0438\u0442\u044c \u0444\u043e\u0440\u043c\u0443<\/div><style>.kadence-form-3754_2f0a81-e6 .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n<!-- [\/element-3754] -->\n","protected":false},"excerpt":{"rendered":"<p>Weather Sensor Weather sensors are used to measure and monitor environmental meteorological data such as temperature, humidity, wind speed, wind direction, atmospheric pressure, and precipitation. They are widely used in weather stations, agriculture, and environmental monitoring. As a professional meteorological sensor manufacturer, we have an experienced team that can provide customized services to meet your&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":15,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":true,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-3700","page","type-page","status-publish","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"admin","author_link":"https:\/\/www.yantaisensor.com\/ru\/author\/admin"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/pages\/3700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/comments?post=3700"}],"version-history":[{"count":17,"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/pages\/3700\/revisions"}],"predecessor-version":[{"id":6935,"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/pages\/3700\/revisions\/6935"}],"wp:attachment":[{"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/media?parent=3700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}