{"id":1373,"date":"2025-11-08T10:14:15","date_gmt":"2025-11-08T02:14:15","guid":{"rendered":"http:\/\/wp.yantaisensor.com\/?post_type=product&#038;p=1373"},"modified":"2026-05-09T11:57:56","modified_gmt":"2026-05-09T03:57:56","slug":"xf500s-cwb-photovoltaic-power-station-compact-weather-sensor-wireless-solar-radiation-sensor","status":"publish","type":"product","link":"https:\/\/www.yantaisensor.com\/ru\/product\/xf500s-cwb-photovoltaic-power-station-compact-weather-sensor-wireless-solar-radiation-sensor","title":{"rendered":"XF500S-CWB \u0424\u043e\u0442\u043e\u044d\u043b\u0435\u043a\u0442\u0440\u0438\u0447\u0435\u0441\u043a\u0430\u044f \u044d\u043b\u0435\u043a\u0442\u0440\u043e\u0441\u0442\u0430\u043d\u0446\u0438\u044f \u041a\u043e\u043c\u043f\u0430\u043a\u0442\u043d\u044b\u0439 \u0434\u0430\u0442\u0447\u0438\u043a \u043f\u043e\u0433\u043e\u0434\u044b \u0411\u0435\u0441\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u043e\u0439 \u0434\u0430\u0442\u0447\u0438\u043a \u0441\u043e\u043b\u043d\u0435\u0447\u043d\u043e\u0433\u043e \u0438\u0437\u043b\u0443\u0447\u0435\u043d\u0438\u044f"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1373_8213bf-81{margin-top:-30px;}.kb-row-layout-id1373_8213bf-81 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_8213bf-81 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_8213bf-81 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id1373_8213bf-81 > .kt-row-layout-overlay{opacity:0.95;background-color:#f0f2f4;}@media all and (max-width: 1024px){.kb-row-layout-id1373_8213bf-81 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1373_8213bf-81 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_8213bf-81 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_ed1fee-e9 > .kt-inside-inner-col,.kadence-column1373_ed1fee-e9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_ed1fee-e9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_ed1fee-e9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_ed1fee-e9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_ed1fee-e9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_ed1fee-e9{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_ed1fee-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_ed1fee-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_ed1fee-e9\"><div class=\"kt-inside-inner-col\"><style>.kb-gallery-type-thumbslider.kb-gallery-id-1373_0230fb-2b .kt-blocks-carousel-init {margin-bottom:10px;}.kb-gallery-id-1373_0230fb-2b .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1373_0230fb-2b .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-1373_0230fb-2b alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-thumbslider kb-gallery-id-1373_0230fb-2b kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div id=\"kb-slider-1373_0230fb-2b\" class=\"kt-blocks-carousel-init splide kb-blocks-slider kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"4\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-thumb-slider-1373_0230fb-2b\"  data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-gap=\"10px\" data-slider-gap-tablet=\"10px\" data-slider-gap-mobile=\"10px\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9.webp\" data-id=\"3802\" class=\"wp-image-3802 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6.webp\" width=\"800\" height=\"600\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6.webp\" data-id=\"3794\" class=\"wp-image-3794 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4.webp\" width=\"800\" height=\"600\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4.webp\" data-id=\"3792\" class=\"wp-image-3792 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5.webp\" width=\"800\" height=\"600\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5.webp\" data-id=\"3793\" class=\"wp-image-3793 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><div id=\"kb-thumb-slider-1373_0230fb-2b\" class=\"kb-blocks-slider splide kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-speed=\"7000\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-slider-1373_0230fb-2b\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9.webp\" width=\"1024\" height=\"768\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9.webp\" data-id=\"3802\" class=\"wp-image-3802 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9.webp 1200w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-768x576.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6.webp\" width=\"800\" height=\"600\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6.webp\" data-id=\"3794\" class=\"wp-image-3794 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-6-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4.webp\" width=\"800\" height=\"600\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4.webp\" data-id=\"3792\" class=\"wp-image-3792 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-4-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5.webp\" width=\"800\" height=\"600\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5.webp\" data-id=\"3793\" class=\"wp-image-3793 skip-lazy\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-5-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column1373_9161a6-3c > .kt-inside-inner-col,.kadence-column1373_9161a6-3c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_9161a6-3c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_9161a6-3c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_9161a6-3c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_9161a6-3c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_9161a6-3c{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_9161a6-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_9161a6-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_9161a6-3c\"><div class=\"kt-inside-inner-col\">\n<h1 class=\"wp-block-heading has-large-font-size\">XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor<\/h1>\n\n\n\n<p>The XF500S-CWB compact weather station is an instrument used in the field of photovoltaic power stations and new energy monitoring. The product innovatively integrates various meteorological parameters that need to be monitored in the operation and maintenance of photovoltaic power stations into one structure, and can simultaneously measure: atmospheric temperature, relative humidity, component temperature, wind speed, wind direction, atmospheric pressure, solar total radiation POA , and total radiation daily cumulative radiation.<\/p>\n\n\n<style>.kb-table-container1373_ac0fed-26{overflow-x:auto;}.kb-table-container .kb-table1373_ac0fed-26 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table1373_ac0fed-26 caption{text-align:center;}.kb-table-container .kb-table1373_ac0fed-26 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}.kb-table-container .kb-table1373_ac0fed-26 tr:nth-of-type(odd){background-color:rgba(225,225,225,0.55);}.kb-table-container .kb-table1373_ac0fed-26 td, .kb-table1373_ac0fed-26 th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}@media all and (max-width: 1024px){.kb-table-container .kb-table1373_ac0fed-26 td, .kb-table1373_ac0fed-26 th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-table-container .kb-table1373_ac0fed-26 td, .kb-table1373_ac0fed-26 th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-table-container kb-table-container1373_ac0fed-26 wp-block-kadence-table\"><table class=\"kb-table kb-table1373_ac0fed-26\">\n<tr class=\"kb-table-row kb-table-row1373_dbd34a-32\">\n<td class=\"kb-table-data kb-table-data1373_416d96-1e\">\n\n<p><strong>Parameter<\/strong><\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1373_e8b225-48\">\n\n<p><strong>Specification<\/strong><\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1373_9ec274-c0\">\n<td class=\"kb-table-data kb-table-data1373_7df26a-e6\">\n\n<p>Model<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1373_145006-1f\">\n\n<p>XF500S-CWB<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1373_2c63ee-75\">\n<td class=\"kb-table-data kb-table-data1373_5b7f74-6d\">\n\n<p>Material<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1373_c025ee-1e\">\n\n<p>plastic<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1373_11fc75-fa\">\n<td class=\"kb-table-data kb-table-data1373_a4db08-a5\">\n\n<p>Multiple Output<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1373_b58d58-56\">\n\n<p>RS485\uff08ModBusRTU\uff09<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1373_c1d90b-df\">\n<td class=\"kb-table-data kb-table-data1373_970fba-e2\">\n\n<p>Ingress Protection<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1373_ad1117-40\">\n\n<p>IP65<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1373_bdfd5b-58\">\n<td class=\"kb-table-data kb-table-data1373_c0ee1b-2c\">\n\n<p>Power Supply<\/p>\n\n<\/td>\n\n<td class=\"kb-table-data kb-table-data1373_a84621-23\">\n\n<p>DC12-24V<\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n<!-- [element-4655] --><style>.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{display:flex;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{padding-left:0px;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col,.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4655_6bf1b4-cc{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4655_6bf1b4-cc{position:relative;}.kadence-column4655_6bf1b4-cc, .kt-inside-inner-col > .kadence-column4655_6bf1b4-cc:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4655_6bf1b4-cc{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column4655_6bf1b4-cc{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4655_6bf1b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4655_6bf1b4-cc\"><div class=\"kt-inside-inner-col\"><style>#kt-modal4655_8bf53c-60 .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px px;}#kt-modal4655_8bf53c-60 .kt-blocks-modal-link:hover, #kt-modal4655_8bf53c-60 .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal4655_8bf53c-60 .kt-modal-overlay, #kt-target-modal4655_8bf53c-60 .kt-modal-overlay, .kb-modal-content4655_8bf53c-60 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{width:45%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal4655_8bf53c-60 .kt-modal-close svg, #kt-target-modal4655_8bf53c-60 .kt-modal-close svg, .kb-modal-content4655_8bf53c-60 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal4655_8bf53c-60 .kt-modal-close svg, #kt-target-modal4655_8bf53c-60 .kt-modal-close svg, .kb-modal-content4655_8bf53c-60 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal4655_8bf53c-60 .kt-modal-container, #kt-target-modal4655_8bf53c-60 .kt-modal-container, .kb-modal-content4655_8bf53c-60 .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal4655_8bf53c-60 .kt-modal-close svg, #kt-target-modal4655_8bf53c-60 .kt-modal-close svg, .kb-modal-content4655_8bf53c-60 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal aligncenter kt-modal-linkalign-left\" id=\"kt-modal4655_8bf53c-60\"><div id=\"kt-target-modal4655_8bf53c-60\" class=\"kb-modal-content4655_8bf53c-60 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal4655_8bf53c-60-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-4655_273dee-56 .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);}.kadence-form-4655_273dee-56 .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-4655_273dee-56 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_4655_273dee-56_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_4655_273dee-56_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_4655_273dee-56_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_4655_273dee-56_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_4655_273dee-56_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_4655_273dee-56_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_4655_273dee-56_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_4655_273dee-56_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"4655_273dee-56\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"4655\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\"><strong>SUBMIT<\/strong><\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">\u041f\u043e\u0436\u0430\u043b\u0443\u0439\u0441\u0442\u0430, \u0432\u043a\u043b\u044e\u0447\u0438\u0442\u0435 JavaScript \u0432 \u0432\u0430\u0448\u0435\u043c \u0431\u0440\u0430\u0443\u0437\u0435\u0440\u0435, \u0447\u0442\u043e\u0431\u044b \u043e\u0442\u043f\u0440\u0430\u0432\u0438\u0442\u044c \u0444\u043e\u0440\u043c\u0443<\/div><style>.kadence-form-4655_273dee-56 .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal4655_8bf53c-60\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-4655] -->\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_2e4fe5-0b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_2e4fe5-0b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_2e4fe5-0b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1373_2e4fe5-0b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_2e4fe5-0b > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1373_2e4fe5-0b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_2e4fe5-0b alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_bc34da-b4 > .kt-inside-inner-col,.kadence-column1373_bc34da-b4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_bc34da-b4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_bc34da-b4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_bc34da-b4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_bc34da-b4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_bc34da-b4{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_bc34da-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_bc34da-b4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_bc34da-b4\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\" style=\"text-transform:capitalize\">Introduction<\/h2>\n\n\n\n<p>XF500S-CWB Wireless Solar Radiation Sensor is a compact, highly integrated solution designed for accurate solar radiation and environmental monitoring in photovoltaic power stations and other outdoor applications. Built for long-term, unattended operation, it combines stable measurement performance with low power consumption and wireless data transmission, making it well suited for distributed and remote monitoring systems.<\/p>\n\n\n\n<p>With a small-size, modular structure and no moving parts, the sensor offers excellent mechanical stability, high reliability, and minimal maintenance requirements. The integrated design simplifies installation while improving resistance to harsh outdoor conditions, ensuring consistent data performance over time.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_99b9c1-79 > .kt-inside-inner-col,.kadence-column1373_99b9c1-79 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_99b9c1-79 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_99b9c1-79 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_99b9c1-79 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_99b9c1-79 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_99b9c1-79{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_99b9c1-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_99b9c1-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_99b9c1-79\"><div class=\"kt-inside-inner-col\"><style>.kb-image1373_c4aaf9-79.kb-image-is-ratio-size, .kb-image1373_c4aaf9-79 .kb-image-is-ratio-size{max-width:539px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1373_c4aaf9-79.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1373_c4aaf9-79 .kb-image-is-ratio-size{align-self:unset;}.kb-image1373_c4aaf9-79 figure{max-width:539px;}.kb-image1373_c4aaf9-79 .image-is-svg, .kb-image1373_c4aaf9-79 .image-is-svg img{width:100%;}.kb-image1373_c4aaf9-79 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image1373_c4aaf9-79\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1450\" height=\"820\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts.webp\" alt=\"Wireless Solar Radiation Sensor Parts\" class=\"kb-img wp-image-3806\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts.webp 1450w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts-300x170.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts-1024x579.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts-768x434.webp 768w\" sizes=\"auto, (max-width: 1450px) 100vw, 1450px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_be469b-c9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_be469b-c9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_be469b-c9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_be469b-c9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_be469b-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_be469b-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_be469b-c9 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_b8b76d-2a > .kt-inside-inner-col,.kadence-column1373_b8b76d-2a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_b8b76d-2a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_b8b76d-2a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_b8b76d-2a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_b8b76d-2a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_b8b76d-2a{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_b8b76d-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_b8b76d-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_b8b76d-2a\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-large-font-size\">details Show<\/h2>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-1373_7b54f2-27{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-1373_7b54f2-27 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-1373_7b54f2-27 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1373_7b54f2-27 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-1373_7b54f2-27 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-1373_7b54f2-27 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-7.webp\" width=\"800\" height=\"600\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-7.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-7.webp\" data-id=\"3795\" class=\"wp-image-3795\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-7-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-7-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-3.webp\" width=\"800\" height=\"600\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-3.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-3.webp\" data-id=\"3791\" class=\"wp-image-3791\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-3.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-3-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-3-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts-2.webp\" width=\"944\" height=\"667\" alt=\"Wireless Solar Radiation Sensor\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts-2.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts-2.webp\" data-id=\"3808\" class=\"wp-image-3808\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts-2.webp 944w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts-2-300x212.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wireless-Solar-Radiation-Sensor-Parts-2-768x543.webp 768w\" sizes=\"auto, (max-width: 944px) 100vw, 944px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-2.webp\" width=\"800\" height=\"600\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor (1)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-2.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-2.webp\" data-id=\"3790\" class=\"wp-image-3790\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-2.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-2-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-2-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_1efa49-47 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_1efa49-47 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_1efa49-47 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-sm, 1rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_1efa49-47 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_1efa49-47 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_1efa49-47 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_1efa49-47 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_3ec2c9-3e > .kt-inside-inner-col,.kadence-column1373_3ec2c9-3e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_3ec2c9-3e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_3ec2c9-3e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_3ec2c9-3e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_3ec2c9-3e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_3ec2c9-3e{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_3ec2c9-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_3ec2c9-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_3ec2c9-3e\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-large-font-size\">specifications<\/h2>\n\n\n\n<p>To meet different project requirements, the sensor supports customized design, including parameter configuration, communication methods, and system integration options. Customers are welcome to contact our technical team for tailored solutions and professional support.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td>Parameters<\/td><td>Measuring Range<\/td><td>Accuracy<\/td><td>Resolution<\/td><td>Sampling Frequency<\/td><\/tr><tr><td>Ambient Temperature<\/td><td>-40-85\u2103<\/td><td>\u00b10.3\u2103@25\u2103<\/td><td>0.01\u2103<\/td><td>1HZ<\/td><\/tr><tr><td>Relative Humidity<\/td><td>0-100%RH<\/td><td>\u00b13%RH(&lt;80%RH, No Condensation)<\/td><td>0.01%RH<\/td><td>1HZ<\/td><\/tr><tr><td>Component Temperature<\/td><td>-20\u2103\uff5e+80\u2103<\/td><td>\u2264 \u00b10.2\u2103<\/td><td>0.1\u2103<\/td><td>1HZ<\/td><\/tr><tr><td>Wind Speed<\/td><td>0-60m\/s<\/td><td>\u00b1\uff080.3+0.03V\uff09M\/S\uff1bV\u226430M\/S\u00b1\uff080.3+0.05V\uff09M\/S;V\u226530M\/S(V stands for standard wind speed in a wind tunnel)<\/td><td>0.01m\/s<\/td><td>4HZ<\/td><\/tr><tr><td>Wind Direction<\/td><td>0-359.9\u00b0<\/td><td>\u00b13\u00b0(when Wind Speed =10m\/s)<\/td><td>0.1\u00b0<\/td><td>4HZ<\/td><\/tr><tr><td>Atmospheric Pressure<\/td><td>500-1100hPa<\/td><td>\u00b10.5hPa\uff0825\u2103\uff0c950-1100hPa\uff09<\/td><td>0.1hPa<\/td><td>1HZ<\/td><\/tr><tr><td>Total Solar Radiation POA<\/td><td>0~2000W\/m2<\/td><td>\u2264 \u00b13%<\/td><td>1W\/m2<\/td><td>1HZ<\/td><\/tr><tr><td>Operating Temperature<\/td><td colspan=\"4\">-40\u2103\u201480\u2103<\/td><\/tr><tr><td>Output<\/td><td colspan=\"4\">Standard product with RS485 interface, ModbusRTU;Customizable option SDI-12(Extra costs apply)<\/td><\/tr><tr><td>Maximum Output Frequency<\/td><td colspan=\"4\">Passive Mode: 1\/S Active Mode: 1\/min<\/td><\/tr><tr><td>Power Supply<\/td><td colspan=\"4\">DC12-24V<\/td><\/tr><tr><td>Solar Radiation Gauge Adjustment Panel<\/td><td colspan=\"4\">Adjustable Range: 0-60\u00b0(General Standard Selection 40\u00b0)<\/td><\/tr><tr><td>Level of Protection<\/td><td colspan=\"4\">IP65<\/td><\/tr><tr><td>Mounting Manner<\/td><td colspan=\"4\">Standard Product is sleeve fixed (Optional: matching parts, extra costs apply, see Accessory and Parts)<\/td><\/tr><tr><td>Fixed Trestle<\/td><td colspan=\"4\">Optional: 1.5 meter, or 1.8 meter bracket (extra cost apply)<\/td><\/tr><tr><td>Cable<\/td><td colspan=\"4\">3 meter cable line (Optional: 10 meter cable line available for extra cost )<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_f79d1e-ec > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_f79d1e-ec > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_f79d1e-ec > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_f79d1e-ec > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-bottom-sep svg{fill:var(--global-palette9, #ffffff)!important;}.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-top-sep{height:100px;}.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-top-sep svg{width:100%;}.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-top-sep svg{fill:var(--global-palette9, #ffffff)!important;}@media all and (max-width: 1024px){.kb-row-layout-id1373_f79d1e-ec > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id1373_f79d1e-ec > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id1373_f79d1e-ec .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_f79d1e-ec alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_625a89-b7 > .kt-inside-inner-col,.kadence-column1373_625a89-b7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_625a89-b7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_625a89-b7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_625a89-b7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_625a89-b7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_625a89-b7{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_625a89-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_625a89-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_625a89-b7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1373_2f0018-d9, .wp-block-kadence-advancedheading.kt-adv-heading1373_2f0018-d9[data-kb-block=\"kb-adv-heading1373_2f0018-d9\"]{margin-top:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1.1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1373_2f0018-d9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1373_2f0018-d9[data-kb-block=\"kb-adv-heading1373_2f0018-d9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1373_2f0018-d9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1373_2f0018-d9[data-kb-block=\"kb-adv-heading1373_2f0018-d9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1373_2f0018-d9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1373_2f0018-d9\">Features<\/h2>\n\n\n\n<p class=\"has-text-align-center\">This product features a compact, highly integrated design that ensures measurement accuracy and long-term stability while achieving low power consumption and maintenance-free operation. Employing thermopile-based solar radiation measurement technology, combined with a specially engineered insulated protective cover, it effectively minimizes the impact of ambient temperature on measurement results. The fully modular structure contains no moving parts, enabling straightforward installation and supporting multi-parameter expansion. Suitable for long-term outdoor deployment and diverse application scenarios, it also offers complimentary testing and debugging software for seamless system integration and data validation.<\/p>\n\n\n<style>.kb-row-layout-id1373_787d75-67 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_787d75-67 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_787d75-67 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id1373_787d75-67 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1373_787d75-67 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1373_787d75-67 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_787d75-67 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1373_787d75-67 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1373_787d75-67 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1373_787d75-67 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_787d75-67 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1373_e41d28-b9 > .kt-inside-inner-col,.kadence-column1373_e41d28-b9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_e41d28-b9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_e41d28-b9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_e41d28-b9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_e41d28-b9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_e41d28-b9{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_e41d28-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_e41d28-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_e41d28-b9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1373_0e79e7-80 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1373_0e79e7-80 .kt-info-svg-icon-flip, .kt-info-box1373_0e79e7-80 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1373_0e79e7-80 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1373_0e79e7-80 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_0e79e7-80 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1373_0e79e7-80\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowUpCircle kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"16 12 12 8 8 12\"\/><line x1=\"12\" y1=\"16\" x2=\"12\" y2=\"8\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Compact, highly integrated design<\/h3><p class=\"kt-blocks-info-box-text\">Space-saving structure facilitates system integration and multi-point deployment.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_a845a3-c4 > .kt-inside-inner-col,.kadence-column1373_a845a3-c4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_a845a3-c4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_a845a3-c4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_a845a3-c4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_a845a3-c4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_a845a3-c4{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_a845a3-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_a845a3-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_a845a3-c4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1373_a0c259-cd .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1373_a0c259-cd .kt-info-svg-icon-flip, .kt-info-box1373_a0c259-cd .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1373_a0c259-cd .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1373_a0c259-cd .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_a0c259-cd .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1373_a0c259-cd\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Low-power operation<\/h3><p class=\"kt-blocks-info-box-text\">Ideal for solar-powered and long-term unattended applications.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_1b8eb1-9e > .kt-inside-inner-col,.kadence-column1373_1b8eb1-9e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_1b8eb1-9e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_1b8eb1-9e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_1b8eb1-9e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_1b8eb1-9e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_1b8eb1-9e{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_1b8eb1-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_1b8eb1-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_1b8eb1-9e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1373_e46a0d-f5 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1373_e46a0d-f5 .kt-info-svg-icon-flip, .kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1373_e46a0d-f5 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1373_e46a0d-f5 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_e46a0d-f5 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1373_e46a0d-f5\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_box kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M12.89 1.45l8 4A2 2 0 0 1 22 7.24v9.53a2 2 0 0 1-1.11 1.79l-8 4a2 2 0 0 1-1.79 0l-8-4a2 2 0 0 1-1.1-1.8V7.24a2 2 0 0 1 1.11-1.79l8-4a2 2 0 0 1 1.78 0z\"\/><polyline points=\"2.32 6.16 12 11 21.68 6.16\"\/><line x1=\"12\" y1=\"22.76\" x2=\"12\" y2=\"11\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Modular, no moving parts<\/h3><p class=\"kt-blocks-info-box-text\">High reliability and low maintenance costs for demanding outdoor environments.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_1054dd-31 > .kt-inside-inner-col,.kadence-column1373_1054dd-31 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_1054dd-31 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_1054dd-31 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_1054dd-31 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_1054dd-31 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_1054dd-31{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_1054dd-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_1054dd-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_1054dd-31\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1373_f0169e-98 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1373_f0169e-98 .kt-info-svg-icon-flip, .kt-info-box1373_f0169e-98 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1373_f0169e-98 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1373_f0169e-98 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_f0169e-98 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1373_f0169e-98\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_airplay kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M5 17H4a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h16a2 2 0 0 1 2 2v10a2 2 0 0 1-2 2h-1\"\/><polygon points=\"12 15 17 21 7 21 12 15\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Pyroelectric solar radiation measurement<\/h3><p class=\"kt-blocks-info-box-text\">Provides stable response and high measurement accuracy, suitable for photovoltaic and meteorological applications.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_73cb6b-dc > .kt-inside-inner-col,.kadence-column1373_73cb6b-dc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_73cb6b-dc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_73cb6b-dc > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_73cb6b-dc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_73cb6b-dc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_73cb6b-dc{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_73cb6b-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_73cb6b-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_73cb6b-dc\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1373_9a8b15-12 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1373_9a8b15-12 .kt-info-svg-icon-flip, .kt-info-box1373_9a8b15-12 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1373_9a8b15-12 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1373_9a8b15-12 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_9a8b15-12 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1373_9a8b15-12\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_codepen kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"12 2 22 8.5 22 15.5 12 22 2 15.5 2 8.5 12 2\"\/><line x1=\"12\" y1=\"22\" x2=\"12\" y2=\"15.5\"\/><polyline points=\"22 8.5 12 15.5 2 8.5\"\/><polyline points=\"2 15.5 12 8.5 22 15.5\"\/><line x1=\"12\" y1=\"2\" x2=\"12\" y2=\"8.5\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong>Special-process insulated protective cover<\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Effectively reduces environmental thermal interference, enhancing long-term data consistency.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_7a0e92-0d > .kt-inside-inner-col,.kadence-column1373_7a0e92-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_7a0e92-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_7a0e92-0d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_7a0e92-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_7a0e92-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_7a0e92-0d{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_7a0e92-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_7a0e92-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_7a0e92-0d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box1373_5b5f8a-e8 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1373_5b5f8a-e8 .kt-info-svg-icon-flip, .kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box1373_5b5f8a-e8 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box1373_5b5f8a-e8 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box1373_5b5f8a-e8 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1373_5b5f8a-e8\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-flip\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-flip\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit2 kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"16 3 21 8 8 21 3 21 3 16 16 3\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong>Supports parameter expansion and free testing software<\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Expandable for multiple environmental parameters, paired with XF_PcSoftV1.0 software for convenient debugging and system verification.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_8b3b75-5d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_8b3b75-5d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_8b3b75-5d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_8b3b75-5d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_8b3b75-5d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_8b3b75-5d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_8b3b75-5d alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_466bda-c9 > .kt-inside-inner-col,.kadence-column1373_466bda-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_466bda-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_466bda-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_466bda-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_466bda-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_466bda-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_466bda-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_466bda-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_466bda-c9\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\">Application<\/h2>\n\n\n\n<p class=\"has-text-align-center\">XF500S-CWB Photovoltaic Power Station Compact Weather Sensor &amp; Wireless Solar Radiation Sensor is a highly integrated, compact meteorological sensing solution designed for long-term, unattended outdoor deployment. Featuring wireless data transmission, low power consumption, and solar radiation monitoring, it enables accurate, real-time collection of key environmental parameters. The sensor is widely used in renewable energy, agriculture, transportation, and environmental monitoring, providing reliable data support for operational optimization, safety management, and intelligent decision-making across multiple industries.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_9dd111-04 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_9dd111-04 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_9dd111-04 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id1373_9dd111-04 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1373_9dd111-04 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1373_9dd111-04 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_9dd111-04 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1373_9dd111-04 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1373_9dd111-04 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1373_9dd111-04 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_9dd111-04 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_636c0e-c3 > .kt-inside-inner-col,.kadence-column1373_636c0e-c3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_636c0e-c3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_636c0e-c3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_636c0e-c3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_636c0e-c3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_636c0e-c3{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_636c0e-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_636c0e-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_636c0e-c3\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"707\" height=\"530\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Weather-Monitoring-1-edited.webp\" alt=\"Weather Monitoring\" class=\"wp-image-3788\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Weather-Monitoring-1-edited.webp 707w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Weather-Monitoring-1-edited-300x225.webp 300w\" sizes=\"auto, (max-width: 707px) 100vw, 707px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-transform:capitalize\"><strong><strong><strong>Weather Monitoring<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p>Used for site-level and regional-level meteorological parameter monitoring, providing precise data support for weather analysis, early warnings, and climate assessment.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_953182-10 > .kt-inside-inner-col,.kadence-column1373_953182-10 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_953182-10 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_953182-10 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_953182-10 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_953182-10 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_953182-10{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_953182-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_953182-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_953182-10\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"533\" data-id=\"3786\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Micro-environment-Monitoring-edited.webp\" alt=\"Micro-environment Monitoring\" class=\"wp-image-3786\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Micro-environment-Monitoring-edited.webp 711w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Micro-environment-Monitoring-edited-300x225.webp 300w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-transform:capitalize\"><strong><strong><strong>Micro-environment Monitoring<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p>Suitable for monitoring microenvironments in campuses, communities, and critical zones, enabling high-density, granular data collection.<br><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_d404db-54 > .kt-inside-inner-col,.kadence-column1373_d404db-54 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_d404db-54 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_d404db-54 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_d404db-54 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_d404db-54 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_d404db-54{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_d404db-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_d404db-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_d404db-54\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"413\" height=\"310\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Grid-based-Environmental-Monitoring-edited.webp\" alt=\"Grid-based Environmental Monitoring\" class=\"wp-image-3784\" style=\"width:496px;height:auto\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Grid-based-Environmental-Monitoring-edited.webp 413w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Grid-based-Environmental-Monitoring-edited-300x225.webp 300w\" sizes=\"auto, (max-width: 413px) 100vw, 413px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-transform:capitalize\"><strong><strong><strong>Grid-based Environmental Monitoring<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p>Supports multi-node network deployment to build grid-based environmental monitoring systems, enhancing regional environmental awareness.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_04d834-90 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_04d834-90 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_04d834-90 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);}.kb-row-layout-id1373_04d834-90 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1373_04d834-90 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1373_04d834-90 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_04d834-90 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1373_04d834-90 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1373_04d834-90 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1373_04d834-90 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_04d834-90 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_59c3fa-23 > .kt-inside-inner-col,.kadence-column1373_59c3fa-23 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_59c3fa-23 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_59c3fa-23 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_59c3fa-23 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_59c3fa-23 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_59c3fa-23{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_59c3fa-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_59c3fa-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_59c3fa-23\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Smart-Agricultural-Solutions-.webp\" alt=\"Smart Agricultural Solutions\" class=\"wp-image-3674\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Smart-Agricultural-Solutions-.webp 1200w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Smart-Agricultural-Solutions--300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Smart-Agricultural-Solutions--1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Smart-Agricultural-Solutions--768x576.webp 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-transform:capitalize\"><strong><strong><strong>Agricultural Meteorological Monitoring<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p>Real-time monitoring of light and weather conditions provides data for crop growth assessment, irrigation management, and precision agriculture.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_d97a17-cd > .kt-inside-inner-col,.kadence-column1373_d97a17-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_d97a17-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_d97a17-cd > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_d97a17-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_d97a17-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_d97a17-cd{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_d97a17-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_d97a17-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_d97a17-cd\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"3344\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Solar-Radiation-Sensors-Pyranometers-28.webp\" alt=\"Solar Radiation Sensors Pyranometers\" class=\"wp-image-3344\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Solar-Radiation-Sensors-Pyranometers-28.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Solar-Radiation-Sensors-Pyranometers-28-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Solar-Radiation-Sensors-Pyranometers-28-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-transform:capitalize\"><strong><strong><strong>Photovoltaic Environmental Monitoring<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p>Measures solar radiation and environmental parameters to evaluate PV plant operating environments and optimize power generation efficiency.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_a64fb2-5f > .kt-inside-inner-col,.kadence-column1373_a64fb2-5f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_a64fb2-5f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_a64fb2-5f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_a64fb2-5f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_a64fb2-5f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_a64fb2-5f{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_a64fb2-5f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_a64fb2-5f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_a64fb2-5f\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Power-and-Renewable-Energy-Monitoring.webp\" alt=\"Wind Power and Renewable Energy Monitoring\" class=\"wp-image-3154\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Power-and-Renewable-Energy-Monitoring.webp 1200w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Power-and-Renewable-Energy-Monitoring-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Power-and-Renewable-Energy-Monitoring-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Power-and-Renewable-Energy-Monitoring-768x576.webp 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-transform:capitalize\">Wind Power Meteorological Monitoring<\/h3>\n\n\n\n<p>Provides critical meteorological and radiation data support for wind farms, aiding wind power operation analysis and resource assessment.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_88064d-f3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_88064d-f3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_88064d-f3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_88064d-f3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_88064d-f3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_88064d-f3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_88064d-f3 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_98ff8e-88 > .kt-inside-inner-col,.kadence-column1373_98ff8e-88 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_98ff8e-88 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_98ff8e-88 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_98ff8e-88 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_98ff8e-88 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_98ff8e-88{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_98ff8e-88 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_98ff8e-88 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_98ff8e-88\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Wireless Solar Radiation Sensor <strong>Manufacturer<\/strong> and Supplier<\/h2>\n\n\n\n<p>Yantai is a professional manufacturer and supplier of wireless solar radiation sensors, providing reliable sensing solutions for renewable energy, meteorological monitoring, smart agriculture, and environmental applications. Our sensors feature stable wireless transmission, low power consumption, and strong adaptability to outdoor environments, supporting seamless integration into intelligent monitoring systems. We have solid R&amp;D strength and flexible customization capabilities, and a wind tunnel laboratory, delivers sensor solutions tailored to different project needs. Contact our professional team to discuss your application and receive the most suitable solution.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-1373_22fd14-63{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-1373_22fd14-63 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-1373_22fd14-63 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1373_22fd14-63 .kb-slide-item .kb-gal-image-radius img{border-radius:15px 15px 15px 15px;;}<\/style><div class=\"kb-gallery-wrap-id-1373_22fd14-63 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-1373_22fd14-63 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp\" data-id=\"2567\" class=\"wp-image-2567\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-6-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp\" data-description=\"Professional Weather Station Manufacturer and Supplier\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp\" data-id=\"2568\" class=\"wp-image-2568\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-7-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp\" width=\"900\" height=\"598\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp\" data-id=\"2575\" class=\"wp-image-2575\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14-300x199.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-14-768x510.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp\" data-id=\"2571\" class=\"wp-image-2571\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-10-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp\" data-id=\"2572\" class=\"wp-image-2572\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-11-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier (19)\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier (19)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp\" data-id=\"2563\" class=\"wp-image-2563\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-2-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier (19)\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier (19)\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp\" data-id=\"2580\" class=\"wp-image-2580\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-19-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp\" data-alt=\"Professional Weather Station Manufacturer and Supplier\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp\" width=\"900\" height=\"600\" alt=\"Professional Weather Station Manufacturer and Supplier\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp\" data-id=\"2569\" class=\"wp-image-2569\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8.webp 900w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8-300x200.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Professional-Weather-Station-Manufacturer-and-Supplier-8-768x512.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<!-- [element-6641] --><style>.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6641_52f583-39 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6641_52f583-39 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6641_52f583-39 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6641_9208a2-e5 > .kt-inside-inner-col,.kadence-column6641_9208a2-e5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6641_9208a2-e5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6641_9208a2-e5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6641_9208a2-e5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6641_9208a2-e5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6641_9208a2-e5{position:relative;}@media all and (max-width: 1024px){.kadence-column6641_9208a2-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6641_9208a2-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6641_9208a2-e5\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Certificates<\/h2>\n\n\n\n<p class=\"has-text-align-center\">We have CNAS, ISO, CE, and RoHS certifications, and all weather monitoring systems meet rigorous international standards.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-6641_5f28d1-9d{margin:-10px;}.kb-gallery-type-grid.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item{padding:10px;}.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-6641_5f28d1-9d .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{font-size:var(--global-kb-font-size-md, 1.25rem);}.kb-gallery-caption-style-cover-hover.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption, .kb-gallery-caption-style-below.kb-gallery-id-6641_5f28d1-9d .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{background:var(--global-palette1, #3182CE);}<\/style><div class=\"kb-gallery-wrap-id-6641_5f28d1-9d alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-6641_5f28d1-9d kb-gallery-caption-style-below kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS.webp\" data-description=\"CNAS\" data-alt=\"CNAS\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-port34 kb-has-image-ratio-port34\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS-745x1024.webp\" width=\"745\" height=\"1024\" alt=\"CNAS\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS.webp\" data-id=\"2590\" class=\"wp-image-2590\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS-745x1024.webp 745w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS-218x300.webp 218w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS-768x1056.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/CNAS.webp 1000w\" sizes=\"auto, (max-width: 745px) 100vw, 745px\" \/><\/div><\/div><div class=\"kadence-blocks-gallery-item__caption\">CNAS<\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE.webp\" data-description=\"CE\" data-alt=\"CE\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-port34 kb-has-image-ratio-port34\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-725x1024.webp\" width=\"725\" height=\"1024\" alt=\"CE\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE.webp\" data-id=\"6669\" class=\"wp-image-6669\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-725x1024.webp 725w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-212x300.webp 212w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-768x1085.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-1087x1536.webp 1087w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE-8x12.webp 8w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/CE.webp 1200w\" sizes=\"auto, (max-width: 725px) 100vw, 725px\" \/><\/div><\/div><div class=\"kadence-blocks-gallery-item__caption\">CE<\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001.webp\" data-description=\"ISO9001\" data-alt=\"ISO9001\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-port34 kb-has-image-ratio-port34\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001-718x1024.webp\" width=\"718\" height=\"1024\" alt=\"ISO9001\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001.webp\" data-id=\"2591\" class=\"wp-image-2591\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001-718x1024.webp 718w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001-210x300.webp 210w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001-768x1095.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/ISO9001.webp 1000w\" sizes=\"auto, (max-width: 718px) 100vw, 718px\" \/><\/div><\/div><div class=\"kadence-blocks-gallery-item__caption\">ISO9001<\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS.webp\" data-description=\"RoHS\" data-alt=\"RoHS\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-port34 kb-has-image-ratio-port34\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-725x1024.webp\" width=\"725\" height=\"1024\" alt=\"RoHS\" data-full-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS.webp\" data-light-image=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS.webp\" data-id=\"6671\" class=\"wp-image-6671\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-725x1024.webp 725w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-212x300.webp 212w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-768x1085.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-1087x1536.webp 1087w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS-8x12.webp 8w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2026\/05\/ROHS.webp 1200w\" sizes=\"auto, (max-width: 725px) 100vw, 725px\" \/><\/div><\/div><div class=\"kadence-blocks-gallery-item__caption\">RoHS<\/div><\/a><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div><!-- [\/element-6641] -->\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1373_446d5f-00{margin-top:var(--global-kb-spacing-lg, 3rem);}.kb-row-layout-id1373_446d5f-00 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_446d5f-00 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_446d5f-00 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_446d5f-00 > .kt-row-layout-overlay{opacity:0.35;}@media all and (max-width: 1024px){.kb-row-layout-id1373_446d5f-00 > .kt-row-column-wrap{padding-top:60px;padding-right:150px;padding-bottom:60px;padding-left:150px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_446d5f-00 > .kt-row-column-wrap{padding-top:40px;padding-right:30px;padding-bottom:40px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_446d5f-00 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_bd9d81-9b > .kt-inside-inner-col,.kadence-column1373_bd9d81-9b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_bd9d81-9b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_bd9d81-9b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_bd9d81-9b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_bd9d81-9b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_bd9d81-9b{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_bd9d81-9b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_bd9d81-9b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_bd9d81-9b inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id1373_60da87-01 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_60da87-01 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_60da87-01 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1373_60da87-01 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_60da87-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_60da87-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_60da87-01 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1373_2f818b-c4 > .kt-inside-inner-col,.kadence-column1373_2f818b-c4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_2f818b-c4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_2f818b-c4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_2f818b-c4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_2f818b-c4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_2f818b-c4{position:relative;}.kadence-column1373_2f818b-c4, .kt-inside-inner-col > .kadence-column1373_2f818b-c4:not(.specificity){margin-right:30px;}@media all and (max-width: 1024px){.kadence-column1373_2f818b-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1373_2f818b-c4, .kt-inside-inner-col > .kadence-column1373_2f818b-c4:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column1373_2f818b-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1373_2f818b-c4, .kt-inside-inner-col > .kadence-column1373_2f818b-c4:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_2f818b-c4 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1373_69786b-57, .wp-block-kadence-advancedheading.kt-adv-heading1373_69786b-57[data-kb-block=\"kb-adv-heading1373_69786b-57\"]{text-align:left;font-size:var(--global-kb-font-size-lg, 2rem);font-weight:500;font-style:normal;font-family:var( --global-heading-font-family, inherit );text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading1373_69786b-57 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1373_69786b-57[data-kb-block=\"kb-adv-heading1373_69786b-57\"] mark.kt-highlight{font-style:normal;color:var(--global-palette1, #3182CE);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1373_69786b-57 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1373_69786b-57[data-kb-block=\"kb-adv-heading1373_69786b-57\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1373_69786b-57, .wp-block-kadence-advancedheading.kt-adv-heading1373_69786b-57[data-kb-block=\"kb-adv-heading1373_69786b-57\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 class=\"kt-adv-heading1373_69786b-57 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1373_69786b-57\">FAQs<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column1373_2b06b5-e6 > .kt-inside-inner-col,.kadence-column1373_2b06b5-e6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_2b06b5-e6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_2b06b5-e6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_2b06b5-e6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_2b06b5-e6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_2b06b5-e6{position:relative;}.kadence-column1373_2b06b5-e6, .kt-inside-inner-col > .kadence-column1373_2b06b5-e6:not(.specificity){margin-left:0px;}@media all and (max-width: 1024px){.kadence-column1373_2b06b5-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1373_2b06b5-e6, .kt-inside-inner-col > .kadence-column1373_2b06b5-e6:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column1373_2b06b5-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1373_2b06b5-e6, .kt-inside-inner-col > .kadence-column1373_2b06b5-e6:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_2b06b5-e6 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1373_631cd0-f5, .wp-block-kadence-advancedheading.kt-adv-heading1373_631cd0-f5[data-kb-block=\"kb-adv-heading1373_631cd0-f5\"]{text-align:left;font-style:normal;font-family:-apple-system,BlinkMacSystemFont,\"Segoe UI\",Roboto,Oxygen-Sans,Ubuntu,Cantarell,\"Helvetica Neue\",sans-serif, \"Apple Color Emoji\", \"Segoe UI Emoji\", \"Segoe UI Symbol\";}.wp-block-kadence-advancedheading.kt-adv-heading1373_631cd0-f5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1373_631cd0-f5[data-kb-block=\"kb-adv-heading1373_631cd0-f5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1373_631cd0-f5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1373_631cd0-f5[data-kb-block=\"kb-adv-heading1373_631cd0-f5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1373_631cd0-f5 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1373_631cd0-f5\">Through the following FAQs, you can gain clear insights into key information regarding the product&#8217;s installation deployment, measurement capabilities, system integration, and application compatibility, providing valuable reference for project decision-making and solution design.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_896c44-eb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_896c44-eb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_896c44-eb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_896c44-eb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_896c44-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_896c44-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_896c44-eb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1373_60f4de-3b > .kt-inside-inner-col,.kadence-column1373_60f4de-3b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_60f4de-3b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_60f4de-3b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_60f4de-3b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_60f4de-3b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_60f4de-3b{position:relative;}.kadence-column1373_60f4de-3b, .kt-inside-inner-col > .kadence-column1373_60f4de-3b:not(.specificity){margin-right:30px;}@media all and (max-width: 1024px){.kadence-column1373_60f4de-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1373_60f4de-3b, .kt-inside-inner-col > .kadence-column1373_60f4de-3b:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column1373_60f4de-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1373_60f4de-3b, .kt-inside-inner-col > .kadence-column1373_60f4de-3b:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_60f4de-3b inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id1373_93ec33-33 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:8px;display:grid;grid-template-columns:repeat(2, minmax(0, 1fr));}.kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner{border-top:0px solid var(--global-palette1, #3182CE);border-right:0px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:0px solid var(--global-palette1, #3182CE);background:rgba(255,255,255,0);padding-top:20px;padding-right:50px;padding-bottom:20px;padding-left:0px;}.kt-accordion-id1373_93ec33-33 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette6, #718096);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255,255,255,0);line-height:24px;font-family:var( --global-heading-font-family, inherit );font-weight:400;color:var(--global-palette3, #1A202C);padding-top:14px;padding-right:10px;padding-bottom:10px;padding-left:0px;}.kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette5, #4A5568);}.kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner, .kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner h1, .kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner h2, .kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner h3, .kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner h4, .kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner h5, .kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner h6{color:var(--global-palette3, #1A202C);}.kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner a{color:var(--global-palette1, #3182CE);}.kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner a:hover{color:var(--global-palette2, #2B6CB0);}.kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette5, #4A5568);}.kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:rgba(255,255,255,0);}.kt-accordion-id1373_93ec33-33 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1373_93ec33-33 .kt-blocks-accordion-header:focus-visible{background:rgba(255,255,255,0);border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}.kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:rgba(255,255,255,0);}.kt-accordion-id1373_93ec33-33 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1373_93ec33-33 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{background:rgba(255,255,255,0);border-top-color:rgba(255,255,255,0);border-top-style:solid;border-right-color:rgba(255,255,255,0);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:rgba(255,255,255,0);border-left-style:solid;}.kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1373_93ec33-33:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:rgba(255,255,255,0);}@media all and (max-width: 1024px){.kt-accordion-id1373_93ec33-33 .kt-accordion-inner-wrap{display:block;}}@media all and (max-width: 1024px){.kt-accordion-id1373_93ec33-33 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:8px;}}@media all and (max-width: 1024px){.kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner{border-top:0px solid var(--global-palette1, #3182CE);border-right:0px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:0px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 1024px){.kt-accordion-id1373_93ec33-33 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette6, #718096);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id1373_93ec33-33 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1373_93ec33-33 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id1373_93ec33-33 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1373_93ec33-33 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:rgba(255,255,255,0);border-top-style:solid;border-right-color:rgba(255,255,255,0);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:rgba(255,255,255,0);border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id1373_93ec33-33 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1373_93ec33-33 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:8px;}.kt-accordion-id1373_93ec33-33 .kt-accordion-panel-inner{border-top:0px solid var(--global-palette1, #3182CE);border-right:0px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:0px solid var(--global-palette1, #3182CE);}.kt-accordion-id1373_93ec33-33 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette6, #718096);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}.kt-accordion-id1373_93ec33-33 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1373_93ec33-33 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}.kt-accordion-id1373_93ec33-33 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1373_93ec33-33 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:rgba(255,255,255,0);border-top-style:solid;border-right-color:rgba(255,255,255,0);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:rgba(255,255,255,0);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1373_93ec33-33 kt-accordion-has-6-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane1373_b248a3-4d\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q: What parameters can the XF500S-CWB monitor? Does it support expansion?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1373_936efa-2c, .wp-block-kadence-advancedheading.kt-adv-heading1373_936efa-2c[data-kb-block=\"kb-adv-heading1373_936efa-2c\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1373_936efa-2c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1373_936efa-2c[data-kb-block=\"kb-adv-heading1373_936efa-2c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1373_936efa-2c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1373_936efa-2c[data-kb-block=\"kb-adv-heading1373_936efa-2c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1373_936efa-2c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1373_936efa-2c\">This sensor monitors core meteorological parameters such as solar radiation and supports expansion to track multiple environmental parameters based on project requirements, meeting the needs of photovoltaic and comprehensive meteorological monitoring applications.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane1373_219cfd-85\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q: Does the XF500S-CWB support wireless communication and system integration?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1373_7f9c69-44, .wp-block-kadence-advancedheading.kt-adv-heading1373_7f9c69-44[data-kb-block=\"kb-adv-heading1373_7f9c69-44\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1373_7f9c69-44 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1373_7f9c69-44[data-kb-block=\"kb-adv-heading1373_7f9c69-44\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1373_7f9c69-44 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1373_7f9c69-44[data-kb-block=\"kb-adv-heading1373_7f9c69-44\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1373_7f9c69-44 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1373_7f9c69-44\">It supports wireless data transmission, facilitating remote deployment and multi-node networking. It can integrate with mainstream monitoring platforms and third-party systems.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane1373_2ed983-64\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q: Is installation and maintenance complex? Is it suitable for long-term outdoor use?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1373_812413-f1, .wp-block-kadence-advancedheading.kt-adv-heading1373_812413-f1[data-kb-block=\"kb-adv-heading1373_812413-f1\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1373_812413-f1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1373_812413-f1[data-kb-block=\"kb-adv-heading1373_812413-f1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1373_812413-f1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1373_812413-f1[data-kb-block=\"kb-adv-heading1373_812413-f1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1373_812413-f1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1373_812413-f1\">Featuring a compact, modular design with no moving parts, it offers simple installation and low maintenance requirements, making it particularly suitable for long-term outdoor and unattended operation.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane1373_e6a905-89\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q: Do you offer free samples?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1373_c17a1e-05, .wp-block-kadence-advancedheading.kt-adv-heading1373_c17a1e-05[data-kb-block=\"kb-adv-heading1373_c17a1e-05\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1373_c17a1e-05 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1373_c17a1e-05[data-kb-block=\"kb-adv-heading1373_c17a1e-05\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1373_c17a1e-05 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1373_c17a1e-05[data-kb-block=\"kb-adv-heading1373_c17a1e-05\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1373_c17a1e-05 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1373_c17a1e-05\">A: Sorry , we do not offer free samples . You should pay for the samples and freight cost.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane1373_76d702-56\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q: What is the measurement principle, and is the data stable and reliable?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1373_5aecbb-be, .wp-block-kadence-advancedheading.kt-adv-heading1373_5aecbb-be[data-kb-block=\"kb-adv-heading1373_5aecbb-be\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1373_5aecbb-be mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1373_5aecbb-be[data-kb-block=\"kb-adv-heading1373_5aecbb-be\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1373_5aecbb-be img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1373_5aecbb-be[data-kb-block=\"kb-adv-heading1373_5aecbb-be\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1373_5aecbb-be wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1373_5aecbb-be\">Solar radiation is measured using the thermopile principle. Combined with a specially engineered insulated protective cover, this effectively minimizes temperature interference, ensuring long-term measurement stability.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane1373_a53db4-86\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q: What is your normal delivery way?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1373_6dbc95-f4, .wp-block-kadence-advancedheading.kt-adv-heading1373_6dbc95-f4[data-kb-block=\"kb-adv-heading1373_6dbc95-f4\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1373_6dbc95-f4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1373_6dbc95-f4[data-kb-block=\"kb-adv-heading1373_6dbc95-f4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1373_6dbc95-f4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1373_6dbc95-f4[data-kb-block=\"kb-adv-heading1373_6dbc95-f4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1373_6dbc95-f4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1373_6dbc95-f4\">A: Goods will be sent DHL \/ FEDEX \/ UPS \/ EMS \/ TNT \/ or other proposed forwarders.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_60b616-0a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_60b616-0a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_60b616-0a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_60b616-0a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_60b616-0a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_60b616-0a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_60b616-0a alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_aa12a5-24 > .kt-inside-inner-col,.kadence-column1373_aa12a5-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_aa12a5-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_aa12a5-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_aa12a5-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_aa12a5-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_aa12a5-24{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_aa12a5-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_aa12a5-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_aa12a5-24\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Related Products<\/h2>\n\n\n<style>.kt-post-loop1373_46ab6c-9f .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop1373_46ab6c-9f .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop1373_46ab6c-9f .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop1373_46ab6c-9f .entry-content:after{height:0px;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-footer a{color:#777777;}.kt-post-loop1373_46ab6c-9f .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop1373_46ab6c-9f .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1373_46ab6c-9f.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop1373_46ab6c-9f kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-none kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"false\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kt-post-slider-item post-1388 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200l-ultrasonic-anemometer-sensor\" aria-label=\"XF200L Ultrasonic Anemometer Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF200L Ultrasonic Anemometer\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200L-Ultrasonic-Anemometer5.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200l-ultrasonic-anemometer-sensor\">XF200L Ultrasonic Anemometer Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1403 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200as-ultrasonic-anemometer\" aria-label=\"XF200AS Ultrasonic Anemometer\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF200AS Ultrasonic Anemometer\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF200AS-Ultrasonic-Anemometer-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf200as-ultrasonic-anemometer\">XF200AS Ultrasonic Anemometer<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1351 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf-cq10-smoke-dust-haze-fog-rain-snow-visibility-sensor\" aria-label=\"XF-CQ10 Smoke Dust Haze Fog Rain Snow Visibility Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"xf cq10 smoke dust haze fog rain snow visibility sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c.jpg 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-300x300.jpg 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-100x100.jpg 100w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-600x600.jpg 600w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-150x150.jpg 150w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/10\/\u80fd\u89c1\u5ea6-5_\u526f\u672c-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf-cq10-smoke-dust-haze-fog-rain-snow-visibility-sensor\">XF-CQ10 Smoke Dust Haze Fog Rain Snow Visibility Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1373 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf500s-cwb-photovoltaic-power-station-compact-weather-sensor-wireless-solar-radiation-sensor\" aria-label=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/xf500s-cwb-photovoltaic-power-station-compact-weather-sensor-wireless-solar-radiation-sensor\">XF500S-CWB Photovoltaic Power Station Compact Weather Sensor Wireless Solar Radiation Sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-2557 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/weather-station-with-multiple-sensors\" aria-label=\"Weather Station With Multiple Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Weather-Station-With-Multiple-Sensors\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Weather-Station-With-Multiple-Sensors-4-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/weather-station-with-multiple-sensors\">Weather Station With Multiple Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1382 product type-product status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/product\/portable-weather-station-automatic\" aria-label=\"RYQ-2 Portable Weather Station Automatic\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Portable Weather Station Automatic\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7-300x300.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7-150x150.webp 150w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/RYQ-2-Portable-Weather-Station-Automatic-7-768x768.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/product\/portable-weather-station-automatic\">RYQ-2 Portable Weather Station Automatic<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_376ebb-53 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_376ebb-53 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_376ebb-53 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_376ebb-53 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_376ebb-53 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_376ebb-53 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_376ebb-53 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_9e072d-2a > .kt-inside-inner-col,.kadence-column1373_9e072d-2a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_9e072d-2a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_9e072d-2a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_9e072d-2a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_9e072d-2a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_9e072d-2a{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_9e072d-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_9e072d-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_9e072d-2a\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Related Articles<\/h2>\n\n\n<style>.kt-post-loop1373_8a7141-15 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop1373_8a7141-15 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop1373_8a7141-15 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop1373_8a7141-15 .entry-content:after{height:0px;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop1373_8a7141-15 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop1373_8a7141-15 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1373_8a7141-15.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop1373_8a7141-15 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-none kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"false\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kt-post-slider-item post-1611 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/best-weather-station-for-farmers\" aria-label=\"Best weather station for farmers\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-for-farmers-1-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"weather station for farmers\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-for-farmers-1-1.webp 1000w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-for-farmers-1-1-300x180.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-for-farmers-1-1-768x461.webp 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/best-weather-station-for-farmers\">Best weather station for farmers<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/ru\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1618 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/automatic-weather-station-india\" aria-label=\"Automatic weather station india\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/\u672a\u6807\u9898-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Automatic weather station\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/\u672a\u6807\u9898-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/\u672a\u6807\u9898-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/\u672a\u6807\u9898-1-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/automatic-weather-station-india\">Automatic weather station india<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/ru\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1624 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/automatic-weather-station-manufacturers\" aria-label=\"Automatic weather station manufacturers\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-manufacturers-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"weather station manufacturers\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-manufacturers-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-manufacturers-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/weather-station-manufacturers-1-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/automatic-weather-station-manufacturers\">Automatic weather station manufacturers<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/ru\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1348 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/automatic-outdoor-integrated-environmental-monitoring-equipment\" aria-label=\"Automatic Outdoor Integrated Environmental Monitoring Equipment\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Environmental Monitoring\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-1024x768.webp 1024w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-768x576.webp 768w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1-1536x1152.webp 1536w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Environmental-Monitoring-1.webp 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/automatic-outdoor-integrated-environmental-monitoring-equipment\">Automatic Outdoor Integrated Environmental Monitoring Equipment<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/ru\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1345 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/sonic-anemometer-high-precision-wind-speed-and-direction-sensor\" aria-label=\"Sonic anemometer &#8211; high-precision wind speed and direction sensor\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Automatic-weather-station-diagram.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Automatic weather station diagram\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Automatic-weather-station-diagram.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Automatic-weather-station-diagram-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/12\/Automatic-weather-station-diagram-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/sonic-anemometer-high-precision-wind-speed-and-direction-sensor\">Sonic anemometer &#8211; high-precision wind speed and direction sensor<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/ru\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1334 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/everything-you-need-to-know-about-ultrasonic-wind-sensors\" aria-label=\"Everything You Need to Know About Ultrasonic Wind Sensors\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Sensors-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Wind Sensors\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Sensors-1.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Sensors-1-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Wind-Sensors-1-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/everything-you-need-to-know-about-ultrasonic-wind-sensors\">Everything You Need to Know About Ultrasonic Wind Sensors<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/ru\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1206 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/what-are-environmental-monitoring-sensors\" aria-label=\"What Are Environmental Monitoring Sensors?\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Environmental-Monitoring-Sensors.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Environmental Monitoring Sensors\" srcset=\"https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Environmental-Monitoring-Sensors.webp 800w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Environmental-Monitoring-Sensors-300x225.webp 300w, https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/Environmental-Monitoring-Sensors-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\/what-are-environmental-monitoring-sensors\">What Are Environmental Monitoring Sensors?<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/www.yantaisensor.com\/ru\/author\/admin\" class=\"kt-blocks-post-author-link fn\">admin<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/www.yantaisensor.com\/ru\/blog\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1373_ac6830-2e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1373_ac6830-2e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1373_ac6830-2e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1373_ac6830-2e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1373_ac6830-2e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1373_ac6830-2e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1373_ac6830-2e alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1373_852951-ce > .kt-inside-inner-col,.kadence-column1373_852951-ce > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1373_852951-ce > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1373_852951-ce > .kt-inside-inner-col{flex-direction:column;}.kadence-column1373_852951-ce > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1373_852951-ce > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1373_852951-ce{position:relative;}@media all and (max-width: 1024px){.kadence-column1373_852951-ce > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1373_852951-ce > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1373_852951-ce\"><div class=\"kt-inside-inner-col\"><!-- [element-3754] --><style>.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3754_74b1c9-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3754_74b1c9-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3754_74b1c9-b9 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3754_4ee816-cd > .kt-inside-inner-col,.kadence-column3754_4ee816-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_4ee816-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_4ee816-cd{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_4ee816-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_4ee816-cd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:32px;line-height:1.1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27, .wp-block-kadence-advancedheading.kt-adv-heading3754_83d87b-27[data-kb-block=\"kb-adv-heading3754_83d87b-27\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 id=\"Contact-us\" class=\"kt-adv-heading3754_83d87b-27 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3754_83d87b-27\">Contact us<\/h2>\n\n\n\n<p>Looking for customized smart sensor solutions? Our team specializes in delivering scalable, flexible, and tailored solutions to meet your specific needs.<\/p>\n\n\n\n<p>Fill out the form now to get a personalized solution. Our experts will provide professional advice and ensure your project runs smoothly. Contact us today to start boosting efficiency!<\/p>\n\n\n<style>.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{display:flex;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col,.kadence-column3754_16f1fe-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_16f1fe-90{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column3754_16f1fe-90 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > *, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column3754_16f1fe-90 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column3754_16f1fe-90 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_16f1fe-90 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"]{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b, .wp-block-kadence-advancedheading.kt-adv-heading3754_6acede-9b[data-kb-block=\"kb-adv-heading3754_6acede-9b\"]{text-align:center!important;}}<\/style>\n<div class=\"kt-adv-heading3754_6acede-9b wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3754_6acede-9b\">Follow Us:<\/div>\n\n\n<style>.kt-svg-icons3754_76542c-39 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons3754_76542c-39{justify-content:flex-start;gap:20px;}@media all and (max-width: 1024px){.wp-block-kadence-icon.kt-svg-icons3754_76542c-39{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons3754_76542c-39 alignnone\"><style>.kt-svg-item-3754_c58179-25 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_c58179-25 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:20px;}.kt-svg-item-3754_c58179-25:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_c58179-25\"><a href=\"https:\/\/www.facebook.com\/ultrasonicwindspeed\/\" class=\"kt-svg-icon-link\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_facebook-n\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-3754_e1d41f-13 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_e1d41f-13 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:17px;}.kt-svg-item-3754_e1d41f-13:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_e1d41f-13\"><a href=\"https:\/\/www.yantaisensor.com\/\" class=\"kt-svg-icon-link\" aria-label=\"Twitter\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_twitterX\"><svg viewBox=\"0 0 1200 1227\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M714.163 519.284L1160.89 0H1055.03L667.137 450.887L357.328 0H0L468.492 681.821L0 1226.37H105.866L515.491 750.218L842.672 1226.37H1200L714.137 519.284H714.163ZM569.165 687.828L521.697 619.934L144.011 79.6944H306.615L611.412 515.685L658.88 583.579L1055.08 1150.3H892.476L569.165 687.854V687.828Z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-3754_12db46-e9 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3754_12db46-e9 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:22px;}.kt-svg-item-3754_12db46-e9:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3754_12db46-e9\"><a href=\"https:\/\/www.youtube.com\/@sensoryantai\" class=\"kt-svg-icon-link\" aria-label=\"YouTube\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_youtube\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3754_395d66-d2 > .kt-inside-inner-col,.kadence-column3754_395d66-d2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_395d66-d2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_395d66-d2{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_395d66-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_395d66-d2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column3754_530ead-5a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column3754_530ead-5a > .kt-inside-inner-col,.kadence-column3754_530ead-5a > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{column-gap:0px;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3754_530ead-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3754_530ead-5a > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column3754_530ead-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3754_530ead-5a{text-align:left;}.kadence-column3754_530ead-5a{position:relative;}@media all and (max-width: 1024px){.kadence-column3754_530ead-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3754_530ead-5a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3754_530ead-5a kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-select-style-field{color:var(--global-palette3, #1A202C);border-width:0px 0px 3px 0px;background:rgba(0, 0, 0, 0);border-color:var(--global-palette2, #2B6CB0);}.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-forms-submit{border-radius:50px;}.kadence-form-3754_2f0a81-e6 .kb-form .kadence-blocks-form-field .kb-forms-submit{text-transform:uppercase;}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-3754_2f0a81-e6 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_0\" id=\"kb_field_3754_2f0a81-e6_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_1\" id=\"kb_field_3754_2f0a81-e6_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_2\" id=\"kb_field_3754_2f0a81-e6_2\" data-label=\"Phone\/WhatsApp\" type=\"text\" placeholder=\"Phone\/WhatsApp\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-2\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><textarea name=\"kb_field_3\" id=\"kb_field_3754_2f0a81-e6_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Message\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"3754_2f0a81-e6\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"3754\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\">Send a Message<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">\u041f\u043e\u0436\u0430\u043b\u0443\u0439\u0441\u0442\u0430, \u0432\u043a\u043b\u044e\u0447\u0438\u0442\u0435 JavaScript \u0432 \u0432\u0430\u0448\u0435\u043c \u0431\u0440\u0430\u0443\u0437\u0435\u0440\u0435, \u0447\u0442\u043e\u0431\u044b \u043e\u0442\u043f\u0440\u0430\u0432\u0438\u0442\u044c \u0444\u043e\u0440\u043c\u0443<\/div><style>.kadence-form-3754_2f0a81-e6 .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n<!-- [\/element-3754] -->\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XF500S-CWB Compact Weather Station is an instrument applied in the field of photovoltaic power station and new energy monitoring. It also can be used together with RYQ-3 photovoltaic enviroment monitoring.<\/p>","protected":false},"featured_media":3802,"menu_order":71,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-1373","product","type-product","status-publish","has-post-thumbnail","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":["https:\/\/www.yantaisensor.com\/wp-content\/uploads\/2025\/11\/XF500S-CWB-Photovoltaic-Power-Station-Compact-Weather-Sensor-Wireless-Solar-Radiation-Sensor-9-1024x768.webp",1024,768,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/product\/1373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":4,"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/product\/1373\/revisions"}],"predecessor-version":[{"id":6784,"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/product\/1373\/revisions\/6784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/media\/3802"}],"wp:attachment":[{"href":"https:\/\/www.yantaisensor.com\/ru\/wp-json\/wp\/v2\/media?parent=1373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}